                       {"id":100111,"date":"2025-03-08T12:23:04","date_gmt":"2025-03-08T18:23:04","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=100111"},"modified":"2025-03-08T12:23:04","modified_gmt":"2025-03-08T18:23:04","slug":"captur4n-a-dos-muj3res-por-pel34r-en-via-publica","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/captur4n-a-dos-muj3res-por-pel34r-en-via-publica\/","title":{"rendered":"Captur4n a dos muj3res por pel34r en v\u00eda p\u00fablica"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>JU\u00c1REZ, N.L.- Elementos de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de Ju\u00e1rez detuvieron a dos mujeres que protagonizaban una ri\u00f1a en la v\u00eda p\u00fablica, en la colonia San Francisco.<br \/>\nLos hechos ocurrieron sobre la calle San Antonio, en su cruce con Santa Antonieta, donde los oficiales fueron alertados por un reporte al C4 sobre una pelea en la zona. Al arribar al lugar, observaron a dos mujeres g01pe\u00e1ndose y forcejeando, por lo que intervinieron de inmediato para controlar la situaci\u00f3n.<br \/>\nLas mujeres fueron identificadas como Alondra Elizabeth &#8220;N&#8221;, de 24 a\u00f1os, y Samira Alejandra &#8220;N&#8221;, de 21, quienes presentaban lesiones visibles a causa de la pel3a. Ambas se acusaron mutuamente de agre51ones f\u00edsicas y verbal3s.<br \/>\nTras verificar la situaci\u00f3n y ante la flagrancia del de1ito de le5iones en ri\u00f1a, los agentes procedieron a su detenci\u00f3n, notific\u00e1ndoles sus derechos y traslad\u00e1ndolas ante el Ministerio\u00a0P\u00fablico.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100112\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2025\/03\/Imagen-de-WhatsApp-2025-03-08-a-las-12.08.13_437d2a17-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2025\/03\/Imagen-de-WhatsApp-2025-03-08-a-las-12.08.13_437d2a17-225x300.jpg 225w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2025\/03\/Imagen-de-WhatsApp-2025-03-08-a-las-12.08.13_437d2a17-768x1023.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2025\/03\/Imagen-de-WhatsApp-2025-03-08-a-las-12.08.13_437d2a17-1153x1536.jpg 1153w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2025\/03\/Imagen-de-WhatsApp-2025-03-08-a-las-12.08.13_437d2a17.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; JU\u00c1REZ, N.L.- Elementos de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de Ju\u00e1rez detuvieron a dos mujeres que protagonizaban una ri\u00f1a en la v\u00eda p\u00fablica, en la colonia San Francisco. Los hechos ocurrieron sobre la calle San Antonio, en su cruce con Santa Antonieta, donde los oficiales fueron alertados por un reporte al C4 [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[3812],"class_list":["post-100111","post","type-post","status-publish","format-standard","hentry","category-seguridad-juarez","tag-colonia-san-francisco"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/100111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=100111"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/100111\/revisions"}],"predecessor-version":[{"id":100116,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/100111\/revisions\/100116"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=100111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=100111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=100111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}