                       {"id":10162,"date":"2019-09-12T20:50:20","date_gmt":"2019-09-13T01:50:20","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=10162"},"modified":"2024-12-11T08:56:16","modified_gmt":"2024-12-11T14:56:16","slug":"flamazo-hiere-a-cuatro","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/flamazo-hiere-a-cuatro\/","title":{"rendered":"Flamazo hiere a cuatro"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10163 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/09\/6869f5df-12ad-46e1-8083-1d4b14120042-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/> \u00a0CD. BENITO JU\u00c1REZ, N.L.-<br \/>\nCuatro personas resultaron heridas ante un flamazo de gas en la colonia Terranova la ma\u00f1ana de ayer jueves.<br \/>\nLos hechos ocurrieron en la calle Monte Sanford en el fraccionamiento arriba mencionado, cuando una familia que se dedica a la venta de tacos, cargaba gas en un cami\u00f3n repartidor.<br \/>\nTrascendi\u00f3 que se solicit\u00f3 el llenado del tanque de gas a un cami\u00f3n-pipa de la empresa Sultana, placas PM 5570-A que acudi\u00f3 a brindar el servicio.<br \/>\nSin embargo, los despachadores pasaron por alto el estado del tanque y cuando se realizaba la maniobra, inesperadamente se produjo un flamazo que alcanz\u00f3 a cuatro personas y prendi\u00f3 la alarma en el barrio.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10165 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/09\/d3731cd9-dbe6-446d-acce-a1dfa53ef05d-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/>Los heridos fueron identificados como Mar\u00eda del Pilar Vicencio Hern\u00e1ndez, de 37 a\u00f1os de edad; tambi\u00e9n result\u00f3 con lesiones Rafael Ben\u00edtez Vicencio de 42 a\u00f1os.<br \/>\nResult\u00f3 con quemaduras Brenda Elizabeth G\u00f3mez Zavala de 37 a\u00f1os de edad y el menor \u00c1ngel Gabriel de 14 a\u00f1os, este \u00faltimo es quien presentaba las lesiones m\u00e1s graves, ya que se consideraron de tercer grado las quemaduras recibidas.<br \/>\nLos adultos heridos fueron trasladados a una cl\u00ednica particular ubicada en la avenida Israel Cavazos y Pablo Livas, mientras que el menor, quien estaba en estado m\u00e1s cr\u00edtico, fue llevado a un nosocomio.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10164 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/09\/d8cb045b-714c-4245-bf9d-e8e9e83c59df-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/>Al lugar de inmediato acudieron elementos de Protecci\u00f3n Civil y de Bomberos para apoyar y acordonar el \u00e1rea para realzar las primeras investigaciones.<br \/>\nTanto el tanque donde se produjo la conflagraci\u00f3n, como la pipa de gas fueron asegurados para saber con exactitud el origen de la explosi\u00f3n y as\u00ed deslindar responsabilidades.<br \/>\nLa agencia del Ministerio P\u00fablico tom\u00f3 cartas en el asunto e iniciar\u00e1 las averiguaciones correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0CD. BENITO JU\u00c1REZ, N.L.- Cuatro personas resultaron heridas ante un flamazo de gas en la colonia Terranova la ma\u00f1ana de ayer jueves. Los hechos ocurrieron en la calle Monte Sanford en el fraccionamiento arriba mencionado, cuando una familia que se dedica a la venta de tacos, cargaba gas en un cami\u00f3n repartidor. Trascendi\u00f3 que se [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":10166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[1088],"class_list":["post-10162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-flamazos-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=10162"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10162\/revisions"}],"predecessor-version":[{"id":68395,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10162\/revisions\/68395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=10162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=10162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=10162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}