                       {"id":102659,"date":"2025-04-28T16:44:20","date_gmt":"2025-04-28T22:44:20","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=102659"},"modified":"2025-04-28T16:44:20","modified_gmt":"2025-04-28T22:44:20","slug":"menor-de-11-meses-sufre-atragantamiento-en-la-colonia-valle-del-roble","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/menor-de-11-meses-sufre-atragantamiento-en-la-colonia-valle-del-roble\/","title":{"rendered":"Menor de 11 meses sufre atragantamiento en la colonia Valle del Roble"},"content":{"rendered":"<p>Cadereyta, N.L. &#8211; Un menor de 11 meses de edad sufri\u00f3 un atragantamiento en la colonia Valle del Roble, sector Retama, lo que moviliz\u00f3 a elementos de Protecci\u00f3n Civil para atender la emergencia.<\/p>\n<p>Al llegar al lugar, los param\u00e9dicos encontraron al menor con obstrucci\u00f3n en la v\u00eda a\u00e9rea por cuerpo extra\u00f1o. Se realizaron cinco golpes interescapulares, lo que provoc\u00f3 un fuerte llanto en el menor. Tras la exploraci\u00f3n, se determin\u00f3 que el menor ten\u00eda una frecuencia ventilatoria normal, sin signos de hipoxia y con coloraci\u00f3n rosada.<\/p>\n<p>Afortunadamente, el menor no sufri\u00f3 mayores complicaciones. Los elementos de Protecci\u00f3n Civil brindaron recomendaciones a los padres para evitar futuros incidentes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta, N.L. &#8211; Un menor de 11 meses de edad sufri\u00f3 un atragantamiento en la colonia Valle del Roble, sector Retama, lo que moviliz\u00f3 a elementos de Protecci\u00f3n Civil para atender la emergencia. Al llegar al lugar, los param\u00e9dicos encontraron al menor con obstrucci\u00f3n en la v\u00eda a\u00e9rea por cuerpo extra\u00f1o. Se realizaron cinco golpes [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":102649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,9],"tags":[13084,2600,10411],"class_list":["post-102659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","category-seguridad-cadereyta","tag-atragantamienro","tag-cadereyta","tag-ultimasnoticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/102659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=102659"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/102659\/revisions"}],"predecessor-version":[{"id":102660,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/102659\/revisions\/102660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/102649"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=102659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=102659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=102659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}