                       {"id":10462,"date":"2019-10-03T12:00:16","date_gmt":"2019-10-03T17:00:16","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=10462"},"modified":"2024-12-11T08:56:20","modified_gmt":"2024-12-11T14:56:20","slug":"asegura-fc-vehiculos-abandonados-en-brecha","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/asegura-fc-vehiculos-abandonados-en-brecha\/","title":{"rendered":"Asegura FC vehiculos abandonados en brecha"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10463 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/10\/71287544_2614786541899539_5202070981689999360_o-300x163.jpg\" alt=\"\" width=\"300\" height=\"163\" \/>Al realizar un patrullaje de vigilancia, elementos de Fuerza Civil aseguraron en dos veh\u00edculos que estaban abandonados y que presuntamente pertenecen a un grupo de la delincuencia organizada en Cadereyta.<\/p>\n<p style=\"text-align: justify;\">El autom\u00f3vil y la camioneta fueron localizados en una brecha ubicada en Camino a Las Misiones.<\/p>\n<p style=\"text-align: justify;\">Autoridades periciales llegaron al lugar para realizar las investigaciones correspondientes e informaron que la camioneta contaba con placas del Estado de Texas, mientras que el autom\u00f3vil no portaba l\u00e1minas.<\/p>\n<p>Fuente: Las Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al realizar un patrullaje de vigilancia, elementos de Fuerza Civil aseguraron en dos veh\u00edculos que estaban abandonados y que presuntamente pertenecen a un grupo de la delincuencia organizada en Cadereyta. El autom\u00f3vil y la camioneta fueron localizados en una brecha ubicada en Camino a Las Misiones. Autoridades periciales llegaron al lugar para realizar las investigaciones [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":10464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,8,9],"tags":[1110,2288],"class_list":["post-10462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","category-seguridad","category-seguridad-cadereyta","tag-fuerza-civil","tag-vehiculos-abandonados"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=10462"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10462\/revisions"}],"predecessor-version":[{"id":68551,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10462\/revisions\/68551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=10462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=10462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=10462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}