                       {"id":109764,"date":"2025-10-10T13:48:32","date_gmt":"2025-10-10T19:48:32","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=109764"},"modified":"2025-10-10T13:48:32","modified_gmt":"2025-10-10T19:48:32","slug":"conductora-choca-contra-camion-estacionado-al-norponiente-de-monterrey","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/conductora-choca-contra-camion-estacionado-al-norponiente-de-monterrey\/","title":{"rendered":"Conductora choca contra cami\u00f3n estacionado al norponiente de Monterrey"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La conductora de un autom\u00f3vil compacto result\u00f3 lesionada luego de aparentemente dormitar y estrellar su veh\u00edculo contra un cami\u00f3n que se encontraba estacionado en calles del norponiente de Monterrey, la ma\u00f1ana del viernes 10 de octubre.Se inform\u00f3 que la mujer lesionada se dirig\u00eda a su trabajo como oficial de Tr\u00e1nsito de Monterrey, esto, acompa\u00f1ada de su hija reci\u00e9n nacida, de entre dos a tres meses de edad, quien sali\u00f3 ilesa al encontrarse en su silla de seguridad.<\/p>\n<p>&nbsp;<\/p>\n<p>Param\u00e9dicos de la Cruz Roja y elementos de Protecci\u00f3n Civil de Monterrey atendieron a la conductora que presentaba algunos golpes, pero no requiri\u00f3 hospitalizaci\u00f3n.<\/p>\n<p>FUENTE: TELEDIARIO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; La conductora de un autom\u00f3vil compacto result\u00f3 lesionada luego de aparentemente dormitar y estrellar su veh\u00edculo contra un cami\u00f3n que se encontraba estacionado en calles del norponiente de Monterrey, la ma\u00f1ana del viernes 10 de octubre.Se inform\u00f3 que la mujer lesionada se dirig\u00eda a su trabajo como oficial de Tr\u00e1nsito de Monterrey, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":109765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[12276],"class_list":["post-109764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/109764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=109764"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/109764\/revisions"}],"predecessor-version":[{"id":109766,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/109764\/revisions\/109766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/109765"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=109764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=109764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=109764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}