                       {"id":112163,"date":"2025-12-29T21:10:06","date_gmt":"2025-12-30T03:10:06","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=112163"},"modified":"2025-12-29T21:10:06","modified_gmt":"2025-12-30T03:10:06","slug":"ejecu7an-a-hombre-en-praderas-de-oriente","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/ejecu7an-a-hombre-en-praderas-de-oriente\/","title":{"rendered":"Ejecu7an a hombre en Praderas de Oriente"},"content":{"rendered":"<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Ju\u00e1rez, N.L.- Un hombre perdi\u00f3 la v1da en la colonia Praderas de Oriente, poco despu\u00e9s de las 5:00 de la tarde de hoy.<\/div>\n<div dir=\"auto\">Los hechos ocurrieron en la calle Desierto de Egipto, de la referida colonia, donde qued\u00f3 muer7o Brandon Manuel Mor\u00e1n, de 27 a\u00f1os de edad.<\/div>\n<div dir=\"auto\">El cuerpo de la v\u00edctima qued\u00f3 en la v\u00eda p\u00fablica, frente a un domicilio, sin embargo hay pocas pistas del o los causantes del atentado.<\/div>\n<div dir=\"auto\">Al lugar arribaron los elementos de la polic\u00eda ministerial y del Instituto de Criminal\u00edstica y Servicios Periciales, quienes iniciaron las primeras investigaciones.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un hombre perdi\u00f3 la v1da en la colonia Praderas de Oriente, poco despu\u00e9s de las 5:00 de la tarde de hoy. Los hechos ocurrieron en la calle Desierto de Egipto, de la referida colonia, donde qued\u00f3 muer7o Brandon Manuel Mor\u00e1n, de 27 a\u00f1os de edad. El cuerpo de la v\u00edctima qued\u00f3 en la [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":112164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-112163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/112163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=112163"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/112163\/revisions"}],"predecessor-version":[{"id":112165,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/112163\/revisions\/112165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/112164"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=112163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=112163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=112163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}