                       {"id":112797,"date":"2026-01-30T15:27:24","date_gmt":"2026-01-30T21:27:24","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=112797"},"modified":"2026-01-30T15:30:07","modified_gmt":"2026-01-30T21:30:07","slug":"encuentran-cuerpo-de-hombre-calcinado-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/encuentran-cuerpo-de-hombre-calcinado-en-juarez\/","title":{"rendered":"Encuentran a hombre calcinado en Ju\u00e1rez"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ju\u00e1rez, N.L.-Una persona calcinada fue encontrada en una zona de la colonia Salvador Ch\u00e1vez en el municipio de Ju\u00e1rez, esto sobre un callej\u00f3n entre las calles 17 de Diciembre y 24 de Marzo cerca de la colonia Jard\u00ednes de la Silla.<br \/>\nLa movilizaci\u00f3n se dio alrededor de las 09:00 horas en donde supuestamente el cuerpo seria localizado por una persona que se dirigia a su trabajo y dio aviso a las autoridades.<br \/>\nHasta el momento se desconoce la identidad de la v\u00edctima quien posiblemente seria una persona en situaci\u00f3n de calle aunque esta informaci\u00f3n no ha sido confirmada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ju\u00e1rez, N.L.-Una persona calcinada fue encontrada en una zona de la colonia Salvador Ch\u00e1vez en el municipio de Ju\u00e1rez, esto sobre un callej\u00f3n entre las calles 17 de Diciembre y 24 de Marzo cerca de la colonia Jard\u00ednes de la Silla. La movilizaci\u00f3n se dio alrededor de las 09:00 horas en donde supuestamente el [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":112793,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-112797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/112797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=112797"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/112797\/revisions"}],"predecessor-version":[{"id":112802,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/112797\/revisions\/112802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/112793"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=112797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=112797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=112797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}