                       {"id":11896,"date":"2019-12-04T18:01:30","date_gmt":"2019-12-05T00:01:30","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=11896"},"modified":"2024-12-11T10:00:43","modified_gmt":"2024-12-11T16:00:43","slug":"recibe-dif-cadereyta-vehiculo-adaptado-para-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/recibe-dif-cadereyta-vehiculo-adaptado-para-personas-con-discapacidad\/","title":{"rendered":"Recibe DIF Cadereyta veh\u00edculo adaptado para personas con discapacidad."},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11898 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/12\/78317738_495272401331900_1916476276479098880_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> Monterrey, N. L.<br \/>\nEl DIF Nuevo Le\u00f3n, a trav\u00e9s de su presidenta Adalina D\u00e1valos de Rodr\u00edguez, entreg\u00f3 20 veh\u00edculos, a igual n\u00famero de municipios, adaptados para el traslado de personas con discapacidad que requieran atenci\u00f3n m\u00e9dica, terapias y consultas.<\/p>\n<p style=\"text-align: justify;\">En el marco del D\u00eda Internacional de las Personas con Discapacidad, y en evento desarrollado en el Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial (CREE), se destac\u00f3 que, en general, fueron 35 las unidades adquiridas por el DIF Nuevo Le\u00f3n, con una inversi\u00f3n de 35 millones de pesos, recurso proveniente del \u201cFondo para la Accesibilidad en el Transporte P\u00fablico para las Personas con Discapacidad\u201d.<\/p>\n<p style=\"text-align: justify;\">Con esta inversi\u00f3n, se explic\u00f3, el objetivo es beneficiar a m\u00e1s de 120 mil personas con discapacidad en todo el territorio estatal.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11899 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/12\/78607731_495271817998625_7252306472640446464_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>\u201cCon esta gran inversi\u00f3n creo que hemos avanzado mucho, yo les dije que me tuvieran paciencia\u201d, precis\u00f3 D\u00e1valos de Rodr\u00edguez.<br \/>\nLos municipios beneficiados, y a los que se hizo entrega del veh\u00edculo y su papeler\u00eda correspondiente fueron: Agualeguas, Allende, An\u00e1huac, Aramberri, Cadereyta, Ci\u00e9nega de Flores, China, Doctor Arroyo, El Carmen, General Ter\u00e1n, Hualahuises, Linares, Los Herreras, Los Ramones, Mar\u00edn, Mier y Noriega, Rayones, Sabinas Hidalgo, Salinas Victoria, y Santiago.<\/p>\n<p style=\"text-align: justify;\">\u201cY qu\u00e9 mejor que hoy, que es D\u00eda Internacional de las Personas con Discapacidad, estamos cumpliendo con todas esas personas que por alguna circunstancia o enfermedad de nacimiento llegaron a ser seres especiales.<br \/>\n\u201cSon ellos los que nos motivan a seguir dando el esfuerzo, seguir buscando y convenciendo a mucha gente para que nos puedan abrir ese coraz\u00f3n y esas puertas para poder traer grandes beneficios\u201d, puntualiz\u00f3 la presidenta del DIF Nuevo Le\u00f3n.<br \/>\nEn total, la dependencia estatal compr\u00f3 10 unidades Splinter, 13 unidades Van Manager, y 12 veh\u00edculos de los denominados Tepee.<\/p>\n<p style=\"text-align: justify;\">Preciso mencionar que los veh\u00edculos Splinter ser\u00e1n entregados a Metrorrey para ampliar el Circuito DIF e incluir a los municipios de Santa Catarina, San Pedro y Garc\u00eda.<\/p>\n<p style=\"text-align: justify;\">Mientras que el resto de las unidades ser\u00e1n para dar servicio a las personas con discapacidad en el DIF estatal y a quienes son atendidos en el CREE.<\/p>\n<p style=\"text-align: justify;\">Al final del evento protocolario de entrega de llaves, Adalina D\u00e1valos, acompa\u00f1ada por las presidentas de los DIF municipales o representantes de las mismas, dio el banderazo de salida a estas unidades. En cuanto a los alcaldes, el \u00fanico presente fue el de Agualeguas, Ignacio Castellanos.<\/p>\n<p style=\"text-align: justify;\">Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, N. L. El DIF Nuevo Le\u00f3n, a trav\u00e9s de su presidenta Adalina D\u00e1valos de Rodr\u00edguez, entreg\u00f3 20 veh\u00edculos, a igual n\u00famero de municipios, adaptados para el traslado de personas con discapacidad que requieran atenci\u00f3n m\u00e9dica, terapias y consultas. En el marco del D\u00eda Internacional de las Personas con Discapacidad, y en evento desarrollado en [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":11897,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,17],"tags":[56,308,850,853,1505],"class_list":["post-11896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-locales-cadereyta","tag-adalina-davalos","tag-blanca-flores","tag-dif-cadereyta","tag-dif-nl","tag-martha-de-la-garza-de-quintanilla"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/11896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=11896"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/11896\/revisions"}],"predecessor-version":[{"id":69279,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/11896\/revisions\/69279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=11896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=11896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=11896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}