                       {"id":12055,"date":"2019-12-12T13:32:12","date_gmt":"2019-12-12T19:32:12","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=12055"},"modified":"2024-12-11T10:00:45","modified_gmt":"2024-12-11T16:00:45","slug":"dan-41-anos-de-carcel-a-un-hombre-por-herir-a-su-ex-pareja-y-asesinar-al-novio-de-ella-en-juarez-nl","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/dan-41-anos-de-carcel-a-un-hombre-por-herir-a-su-ex-pareja-y-asesinar-al-novio-de-ella-en-juarez-nl\/","title":{"rendered":"Dan 41 a\u00f1os de c\u00e1rcel a un hombre por herir a su ex pareja y asesinar al novio de ella en Ju\u00e1rez NL"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12056 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/12\/79437664_1758114914323438_2932201338647347200_n-300x210.jpg\" alt=\"\" width=\"300\" height=\"210\" \/>Ju\u00e1rez, N. L.- Un hombre fue sentenciado a 41 a\u00f1os de prisi\u00f3n tras haber lesionado a su ex pareja y asesinar al novio de la misma el pasado mes de marzo en el Fraccionamiento San Francisco en el municipio de Ju\u00e1rez.<\/p>\n<p style=\"text-align: justify;\">Gerardo Emmanuel, cumplir\u00e1 una condena de 15 a\u00f1os por homicidio simple intencional y 26 a\u00f1os 8 meses, por feminicidio en grado de tentativa. Adem\u00e1s, deber\u00e1 pagar 447 mil 750 pesos por reparaci\u00f3n del da\u00f1o y gastos funerarios.<\/p>\n<p style=\"text-align: justify;\">El crimen ocurri\u00f3 al exterior de un domicilio cuando el se\u00f1alado esper\u00f3 a que ambas personas salieran para despu\u00e9s agredirlas con un arma blanca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N. L.- Un hombre fue sentenciado a 41 a\u00f1os de prisi\u00f3n tras haber lesionado a su ex pareja y asesinar al novio de la misma el pasado mes de marzo en el Fraccionamiento San Francisco en el municipio de Ju\u00e1rez. Gerardo Emmanuel, cumplir\u00e1 una condena de 15 a\u00f1os por homicidio simple intencional y 26 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":12056,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[2129],"class_list":["post-12055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-sentencias-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=12055"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12055\/revisions"}],"predecessor-version":[{"id":69355,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12055\/revisions\/69355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=12055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=12055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=12055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}