                       {"id":12767,"date":"2020-01-29T09:30:33","date_gmt":"2020-01-29T15:30:33","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=12767"},"modified":"2024-12-11T10:00:53","modified_gmt":"2024-12-11T16:00:53","slug":"determina-cee-que-ano-electoral-iniciara-el-7-de-octubre-de-2020","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/determina-cee-que-ano-electoral-iniciara-el-7-de-octubre-de-2020\/","title":{"rendered":"Determina CEE que A\u00f1o Electoral iniciar\u00e1 el 7 de octubre de 2020"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12769 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/01\/a\u00f1o-electoral-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Rumbo a las pr\u00f3ximas elecciones, el Consejo General de la Comisi\u00f3n Estatal Electoral estableci\u00f3 que la primera sesi\u00f3n del inicio del proceso electoral 2020-2021, se realizar\u00e1 el mi\u00e9rcoles 7 de octubre de 2020, cumpliendo as\u00ed con la Ley Electoral, que se\u00f1ala que la CEE abrir\u00e1 su periodo ordinario de actividad electoral durante los primeros 7 d\u00edas de octubre del a\u00f1o anterior al de la jornada electoral, mediante una sesi\u00f3n p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, el periodo ordinario de actividad electoral o a\u00f1o electoral, iniciar\u00e1 el 7 de octubre de 2020 y culminar\u00e1 el 31 de diciembre de 2021; revel\u00f3 la Comisi\u00f3n en su Sesi\u00f3n Ordinaria de este 27 de enero.<\/p>\n<p style=\"text-align: justify;\">Lo anterior, se determin\u00f3 a fin de dar certeza sobre los plazos para el tr\u00e1mite de solicitudes de Consulta Popular que se presenten ante la CEE, y que, en su caso, se celebrar\u00e1n el d\u00eda de la jornada electoral; as\u00ed como para posibles modificaciones a las normas electorales locales; que, de acuerdo a la Constituci\u00f3n Federal, deben ser por lo menos 90 d\u00edas antes de que inicie el proceso electoral en que vayan a aplicarse.<\/p>\n<p style=\"text-align: justify;\">L\u00edmite para presentar peticiones de consulta<br \/>\nQuienes deseen presentar peticiones de consulta a celebrarse en 2021, el \u00f3rgano electoral se\u00f1al\u00f3 que la fecha l\u00edmite para hacerlo es el 9 de julio de 2020; conforme a la normativa electoral, que se\u00f1ala que \u00e9stas podr\u00e1n presentarse ante hasta 90 d\u00edas antes de que inicie el periodo electoral.<\/p>\n<p style=\"text-align: justify;\">La consulta se celebrar\u00e1 preferentemente el d\u00eda de las elecciones, seg\u00fan la Ley de Participaci\u00f3n Ciudadana; y la ciudadan\u00eda que pretenda solicitar una consulta, primero debe presentar un aviso de intenci\u00f3n, y posteriormente, el Presidente de la CEE tendr\u00e1 un plazo no mayor a 10 d\u00edas h\u00e1biles para emitir la constancia respectiva y un formato para la obtenci\u00f3n de firmas.<\/p>\n<p style=\"text-align: justify;\">Dicho formato se enviar\u00e1 al INE para su debida integraci\u00f3n en la Aplicaci\u00f3n M\u00f3vil; y una vez que se cuente con la informaci\u00f3n del Instituto sobre el uso de \u00e9sta, se podr\u00e1 iniciar con la obtenci\u00f3n de firmas de apoyo.<\/p>\n<p style=\"text-align: justify;\">Designan a titular de la Direcci\u00f3n de Fiscalizaci\u00f3n a Partidos Pol\u00edticos<br \/>\nEn la misma Sesi\u00f3n, el organismo design\u00f3 a Martha Magdalena Mart\u00ednez Garza, como Directora de Fiscalizaci\u00f3n a Partidos Pol\u00edticos de la CEE, al determinarse que cuenta con amplia experiencia en la materia electoral y con los conocimientos necesarios para desempe\u00f1ar dicho puesto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rumbo a las pr\u00f3ximas elecciones, el Consejo General de la Comisi\u00f3n Estatal Electoral estableci\u00f3 que la primera sesi\u00f3n del inicio del proceso electoral 2020-2021, se realizar\u00e1 el mi\u00e9rcoles 7 de octubre de 2020, cumpliendo as\u00ed con la Ley Electoral, que se\u00f1ala que la CEE abrir\u00e1 su periodo ordinario de actividad electoral durante los primeros 7 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":12768,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[141,515],"class_list":["post-12767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-ano-electoral","tag-cee"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=12767"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12767\/revisions"}],"predecessor-version":[{"id":69707,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12767\/revisions\/69707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=12767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=12767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=12767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}