                       {"id":13523,"date":"2020-03-02T13:12:30","date_gmt":"2020-03-02T19:12:30","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=13523"},"modified":"2024-12-11T10:01:00","modified_gmt":"2024-12-11T16:01:00","slug":"el-inm-asegura-a-46-migrantes-indocumentados-en-cadereyta","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/el-inm-asegura-a-46-migrantes-indocumentados-en-cadereyta\/","title":{"rendered":"El INM asegura a 46 migrantes indocumentados en Cadereyta"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13524 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/03\/inm-300x207.jpg\" alt=\"\" width=\"300\" height=\"207\" \/>Cadereyta Jim\u00e9nez, N. L.- Personal del Instituto Nacional de Migraci\u00f3n y de la Guardia Nacional aseguraron a unos 46 migrantes indocumentados que viajaban como pasajeros en un autob\u00fas rumbo a la frontera norte, en este municipio.<\/p>\n<p style=\"text-align: justify;\">Los indocumentados fueron llevados en tres unidades van del Instituto Nacional de Migraci\u00f3n luego de que no pudieron comprobar su estancia legal en el Pa\u00eds y al ver que se dirig\u00edan a Reynosa, Tamaulipas, para tratar de llegar a los Estados Unidos.<\/p>\n<p style=\"text-align: justify;\">Los polleros trabsportaban a los migrantes en 2 Suburban y 1 Toyota Sienna.<\/p>\n<p style=\"text-align: justify;\">De los 46 extranjeros, 40 fueron transportados al INM de Reynosa y 6 a las oficinas del Instituto en Nuevo Le\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Del total, 9 adultos y un menor son de nacionalidad guatemalteca, 10 mayores y 3 menores de El Salvador, 16 adultos y 5 menores de Honduras y 2 personas provenientes de Sri Lanka.<\/p>\n<p>Fuente: INM<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N. L.- Personal del Instituto Nacional de Migraci\u00f3n y de la Guardia Nacional aseguraron a unos 46 migrantes indocumentados que viajaban como pasajeros en un autob\u00fas rumbo a la frontera norte, en este municipio. Los indocumentados fueron llevados en tres unidades van del Instituto Nacional de Migraci\u00f3n luego de que no pudieron comprobar [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":13524,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[2365,2366],"class_list":["post-13523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-guardia-nacional","tag-migrantes-cadereyta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/13523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=13523"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/13523\/revisions"}],"predecessor-version":[{"id":70041,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/13523\/revisions\/70041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=13523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=13523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=13523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}