                       {"id":15786,"date":"2020-07-22T15:30:57","date_gmt":"2020-07-22T20:30:57","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=15786"},"modified":"2024-12-11T10:02:33","modified_gmt":"2024-12-11T16:02:33","slug":"aprueba-cabildo-de-cadereyta-nombramientos-para-el-sipinna","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/aprueba-cabildo-de-cadereyta-nombramientos-para-el-sipinna\/","title":{"rendered":"Aprueba Cabildo de Cadereyta nombramientos para el SIPINNA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15787 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/07\/Screenshot_20200722_153005-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/07\/Screenshot_20200722_153005-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/07\/Screenshot_20200722_153005-1024x576.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/07\/Screenshot_20200722_153005-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/07\/Screenshot_20200722_153005-1536x864.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/07\/Screenshot_20200722_153005.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cadereyta Jim\u00e9nez, N.L.- E<span style=\"font-size: 1rem;\">st\u00e1 tarde en Sesi\u00f3n de Cabildo Extraordinaria en el municipio de Caderyta, se nombr\u00f3 como Secretaria Ejecutiva del Sistema\u00a0 de Protecci\u00f3n Integral de Ninos, Ni\u00f1as y Adolescentes en Cadereyta a la licenciada Alpha Miroslava de los Santos Montalvo y como Defensora de los Ninos, Ni\u00f1as y Adolescentes en Cadereyta, a la licenciada Sanjuanita Lizeth Mart\u00ednez Oviedo, en una aprobaci\u00f3n un\u00e1nime por parte del cuerpo colegiado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estos nombramientos solo vienen a reforzar las actividades que ambas funcionarias vienen desempe\u00f1ando desde el pasado 06 de Febrero de 2019, cuando el SIPINNA lleg\u00f3 a esta ciudad.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- Est\u00e1 tarde en Sesi\u00f3n de Cabildo Extraordinaria en el municipio de Caderyta, se nombr\u00f3 como Secretaria Ejecutiva del Sistema\u00a0 de Protecci\u00f3n Integral de Ninos, Ni\u00f1as y Adolescentes en Cadereyta a la licenciada Alpha Miroslava de los Santos Montalvo y como Defensora de los Ninos, Ni\u00f1as y Adolescentes en Cadereyta, a la licenciada [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":15787,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[2682],"class_list":["post-15786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-sipinna-cadereyta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/15786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=15786"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/15786\/revisions"}],"predecessor-version":[{"id":71178,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/15786\/revisions\/71178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/15787"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=15786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=15786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=15786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}