                       {"id":1580,"date":"2018-05-10T23:52:33","date_gmt":"2018-05-10T23:52:33","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=1580"},"modified":"2024-12-11T08:37:12","modified_gmt":"2024-12-11T14:37:12","slug":"detiene-uniformada-a-presunto-homicida","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/detiene-uniformada-a-presunto-homicida\/","title":{"rendered":"Detiene uniformada a presunto homicida"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1582 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/05\/2-7-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" \/>Mat\u00f3 a pasajero que defendi\u00f3 a jovencita de acoso sexual<\/p>\n<p style=\"text-align: justify;\">CD. BENITO JU\u00c1REZ, N.L.-<\/p>\n<p style=\"text-align: justify;\">Elementos de la polic\u00eda municipal de Ju\u00e1rez a bordo de la patrulla 102 lograron la detenci\u00f3n de un individuo que provoc\u00f3 la muerte a un pasajero de la Ruta 68 que intentaba defender a una joven que viajaba a bordo de esta misma unidad y era acosada por el presunto homicida.<\/p>\n<p style=\"text-align: justify;\">Los hechos ocurrieron este mi\u00e9rcoles alrededor de las 20:30 horas cuando la unidad del transporte urbano, n\u00famero econ\u00f3mico 31, circulaba sobre la carretera a Reynosa en su cruce con avenida Coahuila.<\/p>\n<p style=\"text-align: justify;\">Ah\u00ed, los usuarios intentaron detener a Lino R. de 42 a\u00f1os de edad quien iba acosando a una joven pasajera; sin embargo, el presunto agresor logr\u00f3 escapar luego de sacar de su mochila un cuchillo con el cual lesion\u00f3 de muerte a uno de sus captores el cual qued\u00f3 tirado en el pavimento.<\/p>\n<p style=\"text-align: justify;\">A este punto llegaron unidades de bomberos de Ju\u00e1rez para la atenci\u00f3n m\u00e9dica, sin embargo, la persona ya no contaba con signos vitales.<\/p>\n<p style=\"text-align: justify;\">Aunque intent\u00f3 huir corriendo del lugar de inmediato fue localizado por los elementos de la polic\u00eda quienes lo detuvieron y lo llevaron ante las autoridades correspondientes para determinar su situaci\u00f3n legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mat\u00f3 a pasajero que defendi\u00f3 a jovencita de acoso sexual CD. BENITO JU\u00c1REZ, N.L.- Elementos de la polic\u00eda municipal de Ju\u00e1rez a bordo de la patrulla 102 lograron la detenci\u00f3n de un individuo que provoc\u00f3 la muerte a un pasajero de la Ruta 68 que intentaba defender a una joven que viajaba a bordo de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1581,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[52,1199],"class_list":["post-1580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-acosador","tag-homicida"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/1580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=1580"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/1580\/revisions"}],"predecessor-version":[{"id":63859,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/1580\/revisions\/63859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=1580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=1580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=1580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}