                       {"id":17183,"date":"2020-11-04T17:16:23","date_gmt":"2020-11-04T23:16:23","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=17183"},"modified":"2024-12-11T10:02:44","modified_gmt":"2024-12-11T16:02:44","slug":"siguen-y-matan-a-joven-dejan-herido-a-inocente","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/siguen-y-matan-a-joven-dejan-herido-a-inocente\/","title":{"rendered":"Siguen y matan a joven; dejan herido a inocente"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17173 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/11\/IMG-20201104-WA0016-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/11\/IMG-20201104-WA0016-1-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/11\/IMG-20201104-WA0016-1-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/11\/IMG-20201104-WA0016-1.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Juarez, N.L.- Tras ser perseguido por varias calles, un hombre fue asesinado a balazos por delincuentes que iban en dos motocicletas, en Ju\u00e1rez.<\/span><\/p>\n<p>Las balas de los sicarios alcanzaron a un soldador que se encontraba laborando en una casa cercana a la zona de la ejecuci\u00f3n.<\/p>\n<p>El homicidio fue cometido alrededor de las 18:35 horas del lunes en la calle Saboya, cerca del cruce con la Avenida Las Torres, en la Colonia Villas de San Francisco.<\/p>\n<p>Elementos de Protecci\u00f3n Civil de Ju\u00e1rez atendieron el reporte de disparos, y tras revisar a la v\u00edctima determinaron que ya hab\u00eda fallecido.<\/p>\n<p>El hombre asesinado no fue identificado en el lugar, dijo una fuente policiaca.<\/p>\n<p>Coment\u00f3 que la v\u00edctima, de unos 25 a\u00f1os, presentaba una herida de bala en el t\u00f3rax y otra en el hombro izquierdo.<\/p>\n<p>Param\u00e9dicos auxiliaron al soldador, identificado como Al\u00e1n Alf\u00e9rez, de 26 a\u00f1os, a quien trasladaron a un hospital. No se report\u00f3 su estado de salud.<\/p>\n<p>De acuerdo con testigos, la v\u00edctima era perseguida por tres delincuentes que viajaban en dos motocicletas.<\/p>\n<p>Al alcanzarlo, uno de los sicarios le dispar\u00f3 al menos en cinco ocasiones.<\/p>\n<p>Uniformados de la Polic\u00eda de Ju\u00e1rez fueron los primeros en llegar al auxilio y acordonaron el lugar en espera de los agentes ministeriales y peritos de la Fiscal\u00eda General de Justicia.<\/p>\n<p>La ejecuci\u00f3n se cometi\u00f3 a unos 50 metros de un mercado ambulante, por donde pas\u00f3 corriendo la v\u00edctima para intentar huir de los delincuentes.<\/p>\n<p>Los agentes ministeriales interrogaron a algunos vecinos, pero nadie reconoci\u00f3 a la v\u00edctima.<\/p>\n<p>Trascendi\u00f3 que los peritos recolectaron varios casquillos, pero no se revel\u00f3 el calibre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juarez, N.L.- Tras ser perseguido por varias calles, un hombre fue asesinado a balazos por delincuentes que iban en dos motocicletas, en Ju\u00e1rez. Las balas de los sicarios alcanzaron a un soldador que se encontraba laborando en una casa cercana a la zona de la ejecuci\u00f3n. El homicidio fue cometido alrededor de las 18:35 horas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17173,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[929],"class_list":["post-17183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-ejecutados-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=17183"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17183\/revisions"}],"predecessor-version":[{"id":71912,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17183\/revisions\/71912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/17173"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=17183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=17183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=17183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}