                       {"id":17574,"date":"2020-12-08T16:00:26","date_gmt":"2020-12-08T22:00:26","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=17574"},"modified":"2024-12-11T10:02:47","modified_gmt":"2024-12-11T16:02:47","slug":"roban-7-minisplit-cuatro-camaras-y-hasta-el-bebedero-de-una-primaria-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/roban-7-minisplit-cuatro-camaras-y-hasta-el-bebedero-de-una-primaria-en-juarez\/","title":{"rendered":"Roban 7 minisplit, cuatro c\u00e1maras y hasta el bebedero de una primaria en Ju\u00e1rez"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17575 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201208-WA0026-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201208-WA0026-300x187.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201208-WA0026.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>JU\u00c1REZ.- Padres de familia y maestros de una escuela primaria ubicada en Ju\u00e1rez solicitaron mayor vigilancia policiaca, luego de que el plantel fue da\u00f1ado y saqueado por completo por una o m\u00e1s personas la semana pasada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El o los ladrones aprovecharon una madrugada para forzar las puertas de varios salones y sustraer diversos objetos de valor, adem\u00e1s del cableado y el centro de carga.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre lo robado se encuentran siete minisplit, dos impresoras, una copiadora, el sistema de videovigilancia con sus cuatro c\u00e1maras, 20 l\u00e1mparas, un horno de microondas y un bebedero el\u00e9ctrico nuevo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los hechos ocurrieron en la escuela &#8220;Ambrosio Garza Salinas&#8221;, que se ubica en las calles Gonz\u00e1lez Garc\u00eda y Nuevo Le\u00f3n, en la colonia Granja San Pedro, cerca de l\u00edmites con Cadereyta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dicha instituci\u00f3n atiende a alumnos que habitan en dicho sector y en colonias aleda\u00f1as, como San Jos\u00e9, Ismael Flores y La Escondida.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JU\u00c1REZ.- Padres de familia y maestros de una escuela primaria ubicada en Ju\u00e1rez solicitaron mayor vigilancia policiaca, luego de que el plantel fue da\u00f1ado y saqueado por completo por una o m\u00e1s personas la semana pasada. El o los ladrones aprovecharon una madrugada para forzar las puertas de varios salones y sustraer diversos objetos de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17576,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[3043],"class_list":["post-17574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-robos-a-escuelas-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=17574"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17574\/revisions"}],"predecessor-version":[{"id":72120,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17574\/revisions\/72120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/17576"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=17574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=17574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=17574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}