                       {"id":17669,"date":"2020-12-16T10:22:39","date_gmt":"2020-12-16T16:22:39","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=17669"},"modified":"2024-12-11T10:02:48","modified_gmt":"2024-12-11T16:02:48","slug":"libran-detencion-por-tecnicismos-policias-de-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/libran-detencion-por-tecnicismos-policias-de-juarez\/","title":{"rendered":"Libran detenci\u00f3n por tecnicismos polic\u00edas de Ju\u00e1rez"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17671 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201211-WA0008-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201211-WA0008-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201211-WA0008-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2020\/12\/IMG-20201211-WA0008.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- Por errores de procedimiento, dos de los tres polic\u00edas de Ju\u00e1rez detenidos la semana pasada en diversos hechos, recuperaron su libertad.<\/span><\/p>\n<p>Un ex polic\u00eda de Fuerza Civil capturado con uno de los oficiales municipales tambi\u00e9n fue liberado, se inform\u00f3.<\/p>\n<p>Solamente una polic\u00eda qued\u00f3 a disposici\u00f3n de un juez de Control, quien a\u00fan no resuelve su situaci\u00f3n legal, por lo que tambi\u00e9n podr\u00eda quedar en libertad.<\/p>\n<p>La madrugada del viernes, en la Carretera a Reynosa, fue detenido Alejandro R., polic\u00eda de Ju\u00e1rez, y su c\u00f3mplice, identificado como \u00c1ngel I., ex elemento de Fuerza Civil.<\/p>\n<p>Ambos fueron se\u00f1alados en un presunto robo en una quinta en el Ejido La Concepci\u00f3n.<\/p>\n<p>Uniformados de Cadereyta los detuvieron en un veh\u00edculo Toyota Avanza, donde encontraron los objetos que hab\u00edan sido sustra\u00eddos de la quinta, seg\u00fan el afectado.<\/p>\n<p>El domingo, el Ministerio P\u00fablico les imput\u00f3 ante un juez el delito de robo. Sin embargo, al resolver su situaci\u00f3n legal, el juzgador los liber\u00f3 alegando que su detenci\u00f3n hab\u00eda sido ilegal.<\/p>\n<p>El juez determin\u00f3 que, si bien les hab\u00edan encontrado objetos robados, no hab\u00eda un se\u00f1alamiento directo de la v\u00edctima u otro testigo de que ellos cometieron el hurto, asegur\u00f3 una fuente.<\/p>\n<p>La Fiscal\u00eda, se dijo, continuar\u00e1 integrando la carpeta de investigaci\u00f3n.<\/p>\n<p>El otro caso, ocurrido el jueves pasado, polic\u00edas rurales capturaron a Blanca Z., de 29 a\u00f1os; y \u00c9rick Daniel, ambos preventivos de Ju\u00e1rez, cuando presuntamente extorsionaban a un pollero.<\/p>\n<p>Se inform\u00f3 que al Ministerio P\u00fablico s\u00f3lo imput\u00f3 a la mujer y dej\u00f3 en libertad a \u00c9rick, sin revelar los detalles.Blanca fue imputada por chantaje y est\u00e1 en espera de que el juez resuelva ma\u00f1ana su situaci\u00f3n legal.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Por errores de procedimiento, dos de los tres polic\u00edas de Ju\u00e1rez detenidos la semana pasada en diversos hechos, recuperaron su libertad. Un ex polic\u00eda de Fuerza Civil capturado con uno de los oficiales municipales tambi\u00e9n fue liberado, se inform\u00f3. Solamente una polic\u00eda qued\u00f3 a disposici\u00f3n de un juez de Control, quien a\u00fan no [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17670,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[3052],"class_list":["post-17669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-policias-detenidos"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=17669"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17669\/revisions"}],"predecessor-version":[{"id":72164,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17669\/revisions\/72164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/17670"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=17669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=17669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=17669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}