                       {"id":17934,"date":"2021-01-27T14:40:28","date_gmt":"2021-01-27T20:40:28","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=17934"},"modified":"2024-12-11T10:02:50","modified_gmt":"2024-12-11T16:02:50","slug":"visita-presidenta-de-dif-cadereyta-ejido-la-esperanza","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/visita-presidenta-de-dif-cadereyta-ejido-la-esperanza\/","title":{"rendered":"Visita Presidenta de DIF Cadereyta ejido &#8220;La Esperanza&#8221;"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17925 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/01\/IMG-20210127-WA0011-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/01\/IMG-20210127-WA0011-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/01\/IMG-20210127-WA0011-1024x682.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/01\/IMG-20210127-WA0011-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/01\/IMG-20210127-WA0011.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cadereyta Jim\u00e9nez, N.L.- La Presidenta del DIF Municipal, la se\u00f1ora Martha de la Garza, hizo un recorrido en el ejido &#8220;La Esperanza&#8221; con la finalidad de entregar diversos apoyos a adultos mayores y juguetes a los ni\u00f1os.<\/span><\/p>\n<p>Asimismo, di\u00f3 seguimiento a un caso que hab\u00eda detectado en una visita anterior, de un adulto mayor que por su condici\u00f3n delicada de salud, requer\u00eda una silla de ruedas y material de curaci\u00f3n.<br \/>\nLos vecinos se mostraron contentos de ver nuevamente a la presidenta del DIF, a quien le reconocieron que siempre est\u00e1 al pendiente de los jimenenses ya que, a lo largo del a\u00f1o a pesar de la contingencia nunca ha dejado de trabajar.<br \/>\nLa funcionario mencion\u00f3 que siempre es un gusto visitarlos en sus casas porque as\u00ed es como se puede dar cuenta de lo que realmente necesitan y canalizar cada caso al \u00e1rea correspondiente, ya sea del DIF o de Presidencia municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- La Presidenta del DIF Municipal, la se\u00f1ora Martha de la Garza, hizo un recorrido en el ejido &#8220;La Esperanza&#8221; con la finalidad de entregar diversos apoyos a adultos mayores y juguetes a los ni\u00f1os. Asimismo, di\u00f3 seguimiento a un caso que hab\u00eda detectado en una visita anterior, de un adulto mayor que [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[850,1505],"class_list":["post-17934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-dif-cadereyta","tag-martha-de-la-garza-de-quintanilla"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=17934"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17934\/revisions"}],"predecessor-version":[{"id":72292,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/17934\/revisions\/72292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/17924"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=17934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=17934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=17934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}