                       {"id":19513,"date":"2021-05-06T14:08:48","date_gmt":"2021-05-06T20:08:48","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=19513"},"modified":"2024-12-11T10:14:40","modified_gmt":"2024-12-11T16:14:40","slug":"planea-paco-trevino-pluvial-en-paseo-del-sabinal","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/planea-paco-trevino-pluvial-en-paseo-del-sabinal\/","title":{"rendered":"Planea Paco Trevi\u00f1o pluvial en Paseo del Sabinal"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19518 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/05\/IMG-20210506-WA0042-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/05\/IMG-20210506-WA0042-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/05\/IMG-20210506-WA0042-1024x576.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/05\/IMG-20210506-WA0042-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/05\/IMG-20210506-WA0042.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- Ante las inundaciones que sufren en algunos sectores de la Colonia Paseo del Sabinal en \u00e9poca de lluvias, Francisco Trevi\u00f1o, candidato del PRI a la alcald\u00eda de Ju\u00e1rez, anunci\u00f3 a los vecinos que su administraci\u00f3n har\u00e1 los estudios necesarios para realizar una obra pluvial que desfogue el agua.<\/span><\/p>\n<p>La realizaci\u00f3n de un drenaje pluvial se facilitar\u00eda gracias a que la colonia colinda con el R\u00edo Santa Catarina, inform\u00f3 Paco Trevi\u00f1o durante un recorrido casa por casa en este sector.<\/p>\n<p>\u201cNos comentan que a veces en temporadas de lluvia se inunda aqu\u00ed en la entrada de la colonia, y a veces al interior tambi\u00e9n, y bueno, como aqu\u00ed conecta cerca del r\u00edo, pues se facilitar\u00eda una obra pluvial\u201d, se\u00f1al\u00f3 el candidato de la coalici\u00f3n Va Fuerte por Nuevo Le\u00f3n.<\/p>\n<p>Paco Trevi\u00f1o se\u00f1al\u00f3 que el problema de las inundaciones y fuertes corrientes de agua se padecen tambi\u00e9n en otros sectores de Ju\u00e1rez, sobre todo en colonias que se encuentran cerca del cerro, por lo que el tema de los pluviales ser\u00e1 una prioridad en su gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Ante las inundaciones que sufren en algunos sectores de la Colonia Paseo del Sabinal en \u00e9poca de lluvias, Francisco Trevi\u00f1o, candidato del PRI a la alcald\u00eda de Ju\u00e1rez, anunci\u00f3 a los vecinos que su administraci\u00f3n har\u00e1 los estudios necesarios para realizar una obra pluvial que desfogue el agua. La realizaci\u00f3n de un drenaje [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":19519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[2701,1684],"class_list":["post-19513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-elecciones-2021","tag-paco-trevino"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/19513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=19513"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/19513\/revisions"}],"predecessor-version":[{"id":72970,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/19513\/revisions\/72970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/19519"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=19513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=19513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=19513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}