                       {"id":2003,"date":"2018-06-07T23:25:31","date_gmt":"2018-06-07T23:25:31","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=2003"},"modified":"2024-12-11T08:37:15","modified_gmt":"2024-12-11T14:37:15","slug":"ernesto-quintanilla-cadereyta-pide-bacheo-seguridad-y-alumbrado","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/ernesto-quintanilla-cadereyta-pide-bacheo-seguridad-y-alumbrado\/","title":{"rendered":"Ernesto Quintanilla.- \u201cCadereyta pide bacheo,  seguridad y alumbrado\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2004 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/06\/thumbnail_IMG_3037-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>CADEREYTA JIM\u00c9NEZ, N.L.-<br \/>\nEn su recorrido por calles principales de la zona centro de Cadereyta Jim\u00e9nez, Ernesto Quintanilla, Candidato Alcalde por el Partido Verde, escuch\u00f3 a los ciudadanos y confirm\u00f3 las peticiones de otros vecinos de colonias aleda\u00f1as a este Municipio.<br \/>\nLos habitantes de las calles Zaragoza y Matamoros, pidieron al igual que la mayor\u00eda de los vecinos, seguridad p\u00fablica, alumbrado y calles de calidad.<br \/>\n\u201cSon tres principales necesidades de los ciudadanos, seguridad, alumbrado y bacheo, les pido su confianza, su apoyo este primero de julio para demostrarles que con fuerza de voluntad se pueden hacer las cosas\u201d, coment\u00f3 Quintanilla.<br \/>\nAgreg\u00f3 que, trabajando en los temas como Educaci\u00f3n, Deportes, Participaci\u00f3n ciudadana, programas de integraci\u00f3n familiar, tambi\u00e9n atacamos los valores y tendremos un municipio reconocido.<br \/>\n\u201cPETROLEROS CON ERNESTO\u201d: FALY ORTU\u00d1O<br \/>\nLa tarde del martes 5 de junio, Ernesto Quintanilla, Candidato del Partido Verde para la Alcald\u00eda de Cadereyta, recorri\u00f3 la colonia El Rosario en compa\u00f1\u00eda de Rafael Ortu\u00f1o, Secretario General de la Secci\u00f3n 49 de petroleros y militantes del Partido Revolucionario Institucional.<br \/>\nCasa por casa y acompa\u00f1ado de integrantes de su planilla, \u201cEl Bigot\u00f3n\u201d y Faly, estuvieron externando las propuestas de trabajo con los vecinos de este sector, demostrando la coalici\u00f3n Verde-PRI.<br \/>\nCon porras como \u201cpetroleros con Ernesto\u201d, \u201cFaly y Ernesto unidos no ser\u00e1n vencidos\u201d, banderas, y pintando de verde y rojo las calles de la colonia, fue como demostraron que este pr\u00f3ximo primero de julio Ernesto saldr\u00e1 victorioso.<br \/>\n\u201cAgradezco mucho a los amigos Petroleros que hoy se re\u00fanen con un servidor y con su secretario general, vamos juntos a Rescatar Cadereyta y hacer bien las cosas por todos los ciudadanos\u201d, externo Quintanilla.<br \/>\nPor su parte Rafael Ortu\u00f1o comento: \u201dHoy, el primero de julio, demostraremos la unidad, el apoyo y sabemos que Ernesto Quintanilla es la \u00fanica y mejor opci\u00f3n para salir adelante en este municipio, vamos juntos compa\u00f1eros a demostrar que unidos podemos hacer las cosas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CADEREYTA JIM\u00c9NEZ, N.L.- En su recorrido por calles principales de la zona centro de Cadereyta Jim\u00e9nez, Ernesto Quintanilla, Candidato Alcalde por el Partido Verde, escuch\u00f3 a los ciudadanos y confirm\u00f3 las peticiones de otros vecinos de colonias aleda\u00f1as a este Municipio. Los habitantes de las calles Zaragoza y Matamoros, pidieron al igual que la mayor\u00eda [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2005,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[990,1852,1894],"class_list":["post-2003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-ernesto-quintanilla","tag-pri-cadereyta","tag-pvem-cadereyta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/2003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=2003"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/2003\/revisions"}],"predecessor-version":[{"id":64083,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/2003\/revisions\/64083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=2003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=2003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=2003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}