                       {"id":20480,"date":"2021-06-30T14:51:07","date_gmt":"2021-06-30T20:51:07","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=20480"},"modified":"2024-12-11T10:14:58","modified_gmt":"2024-12-11T16:14:58","slug":"frontera-sangrienta-disputan-aduanas-drogas-y-migrantes","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/frontera-sangrienta-disputan-aduanas-drogas-y-migrantes\/","title":{"rendered":"Frontera sangrienta: disputan aduanas, drogas y migrantes"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20478 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/06\/IMG-20210630-WA0039-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/06\/IMG-20210630-WA0039-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/06\/IMG-20210630-WA0039-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/06\/IMG-20210630-WA0039.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Miguel Alem\u00e1n,Tamps.-\u00a0<\/span><\/p>\n<p>La violencia asociada al crimen organizado repunt\u00f3 en Tamaulipas despu\u00e9s de las elecciones del 6 de junio y fuentes lo atribuyen a la disputa entre el C\u00e1rtel del Noreste (CDN) y el C\u00e1rtel del Golfo (CDG) por el control de las aduanas, el narcotr\u00e1fico y el tr\u00e1fico de migrantes.<\/p>\n<p>Apenas ayer, nueve cuerpos baleados, mutilados y uno decapitado fueron tirados en la Carretera Mier-Miguel Alem\u00e1n, luego de un enfrentamiento registrado durante la madrugada.<\/p>\n<p>Este suceso sigue a la matanza indiscriminada de 15 civiles inocentes as\u00ed como cuatro sicarios en Reynosa, el pasado 19 de junio, y a la serie de desapariciones, que podr\u00edan superar las 100, en la Carretera Monterrey-Nuevo Laredo a partir del Kil\u00f3metro 26, conocido como el &#8220;Tramo del terror&#8221;.<\/p>\n<p>Las fuentes se\u00f1alan que la narcoguerra de los c\u00e1rteles se agudiza por tener Nuevo Laredo y Reynosa las aduanas de mayor tr\u00e1fico de carga del Pa\u00eds, que el CDN y el CDG usan para el contrabando de drogas a Texas y ahora est\u00e1n expandiendo el tr\u00e1fico de migrantes.<\/p>\n<p>Las fuentes indicaron que, desde hace m\u00e1s de un a\u00f1o, el CDN, con asiento en Nuevo Laredo, pretende apoderarse de la plaza de Miguel Alem\u00e1n y la llamada &#8220;frontera chica&#8221;.<\/p>\n<p>Esta incluye los municipios de D\u00edaz Ordaz, Camargo, Miguel Alem\u00e1n, Mier y Nueva Ciudad Guerrero, tradicionalmente es poco vigilada por corporaciones policiacas y es zona de paso de contrabandistas de drogas, dinero y armas.<\/p>\n<p>Fuente: El Norte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Alem\u00e1n,Tamps.-\u00a0 La violencia asociada al crimen organizado repunt\u00f3 en Tamaulipas despu\u00e9s de las elecciones del 6 de junio y fuentes lo atribuyen a la disputa entre el C\u00e1rtel del Noreste (CDN) y el C\u00e1rtel del Golfo (CDG) por el control de las aduanas, el narcotr\u00e1fico y el tr\u00e1fico de migrantes. Apenas ayer, nueve cuerpos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":20478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[766,3075,3170],"class_list":["post-20480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-delincuencia-organizada","tag-fuente-el-norte","tag-matanza-miguel-aleman"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/20480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=20480"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/20480\/revisions"}],"predecessor-version":[{"id":73368,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/20480\/revisions\/73368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/20478"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=20480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=20480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=20480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}