                       {"id":20566,"date":"2021-07-05T01:41:47","date_gmt":"2021-07-05T07:41:47","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=20566"},"modified":"2024-12-11T10:15:00","modified_gmt":"2024-12-11T16:15:00","slug":"ejecutan-a-padre-e-hijo-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/ejecutan-a-padre-e-hijo-en-juarez\/","title":{"rendered":"Ejecutan a padre e hijo en Ju\u00e1rez"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20560 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/07\/IMG-20210704-WA0091-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/07\/IMG-20210704-WA0091-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/07\/IMG-20210704-WA0091-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/07\/IMG-20210704-WA0091.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- A dos cuadra de su casa, cuando estaban estacionados en un Oxxo, padre e hijo fueron atacados a balazos, por lo que murieron cuando eran llevados por familiares a un hospital, en Ju\u00e1rez.<\/span><\/p>\n<p>Aunque los occisos fueron identificados en el lugar por sus familiares, la autoridad se reserv\u00f3 sus nombres.<\/p>\n<p>El ataque a balazos fue reportado alrededor de las 00:10 horas, en un Oxxo ubicado sobre la Avenida Las Torres y Jacarandas, en la Colonia Los Encinos.<\/p>\n<p>Se presume, que padre e hijo, quienes son due\u00f1os de un dep\u00f3sito, fueron citados en ese lugar por los criminales, para posteriormente atacarlos a balazos.<\/p>\n<p>Familiares de las v\u00edctimas, al enterarse del ataque, llegaron y los subieron en un auto Sentra con la intenci\u00f3n de llevarlos a un hospital, aunque ya se hab\u00eda solicitado el auxilio de una ambulancia.<\/p>\n<p>Sin embargo, menos de un kil\u00f3metros, sobre la Carretera a Reynosa, a la altura de la Colonia Hacienda Santa Luc\u00eda, el veh\u00edculo se qued\u00f3 sin gasolina.<\/p>\n<p>A ese lugar llegaron socorristas de las ambulancias de la empresa UMT, pero al revisar el cuerpo de los hombres confirmaron que ya no presentaban signos de vida.<\/p>\n<p>Fuente: El Norte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- A dos cuadra de su casa, cuando estaban estacionados en un Oxxo, padre e hijo fueron atacados a balazos, por lo que murieron cuando eran llevados por familiares a un hospital, en Ju\u00e1rez. Aunque los occisos fueron identificados en el lugar por sus familiares, la autoridad se reserv\u00f3 sus nombres. El ataque a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":20560,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[929,3075],"class_list":["post-20566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-ejecutados-juarez","tag-fuente-el-norte"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/20566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=20566"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/20566\/revisions"}],"predecessor-version":[{"id":73408,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/20566\/revisions\/73408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/20560"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=20566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=20566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=20566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}