                       {"id":22018,"date":"2021-09-10T14:34:15","date_gmt":"2021-09-10T20:34:15","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=22018"},"modified":"2024-12-11T10:15:29","modified_gmt":"2024-12-11T16:15:29","slug":"encuentran-un-ejecutado-en-entrada-de-colinas-de-san-juan","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/encuentran-un-ejecutado-en-entrada-de-colinas-de-san-juan\/","title":{"rendered":"Encuentran un ejecutado en entrada de Colinas de San Juan\u00a0"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-22003 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/09\/IMG-20210910-WA0001-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/09\/IMG-20210910-WA0001-300x170.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/09\/IMG-20210910-WA0001.jpg 715w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- Esta ma\u00f1ana se realiz\u00f3 el hallazgo de un cuerpo sin vida a la entrada de la colonia Colinas de San Juan en el municipio de Ju\u00e1rez.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los hechos sucedieron sobre la Carretera Libre a Reynosa Km 20 donde el cuerpo sin vida de un hombre fue encontrado con\u00a0 signos de tortura, semi desnudo, amarrado con cables de pies y manos adem\u00e1s presentar huellas de estrangulamiento con cable met\u00e1lico.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se desconocen datos de los presuntos\u00a0 responsables del hecho y al lugar arribaron elementos de la Polic\u00eda Municipal, Ministeriales as\u00ed como personal de Servicios Periciales.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Esta ma\u00f1ana se realiz\u00f3 el hallazgo de un cuerpo sin vida a la entrada de la colonia Colinas de San Juan en el municipio de Ju\u00e1rez.\u00a0 Los hechos sucedieron sobre la Carretera Libre a Reynosa Km 20 donde el cuerpo sin vida de un hombre fue encontrado con\u00a0 signos de tortura, semi desnudo, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":22002,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[929,3076],"class_list":["post-22018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-ejecutados-juarez","tag-fuente-la-ultima-palabra"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/22018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=22018"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/22018\/revisions"}],"predecessor-version":[{"id":74018,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/22018\/revisions\/74018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/22002"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=22018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=22018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=22018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}