                       {"id":22881,"date":"2021-10-13T18:10:40","date_gmt":"2021-10-14T00:10:40","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=22881"},"modified":"2024-12-11T10:15:47","modified_gmt":"2024-12-11T16:15:47","slug":"detienen-a-dos-con-droga-en-la-eloy-cavazos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/detienen-a-dos-con-droga-en-la-eloy-cavazos\/","title":{"rendered":"Detienen a dos con droga en la Eloy Cavazos"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-22884 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0036-222x300.jpg\" alt=\"\" width=\"222\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0036-222x300.jpg 222w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0036-758x1024.jpg 758w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0036-768x1038.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0036.jpg 947w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/>Ju\u00e1rez, N L.- Fue cerca de las 16:00 horas de hoy mi\u00e9rcoles 13 de octubre que elementos de la Secretaria de Seguridad P\u00fablica de Ju\u00e1rez, recibieron el reporte sobre un veh\u00edculo tipo Mondeo en color arena que circulaba a exceso de velocidad pasandose los sem\u00e1foros en rojo sobre la avenida Eloy Cavazos en direcci\u00f3n al poniente, por lo que al atender el llamado ciudadano e intentar detener el veh\u00edculo este inicio una persecuci\u00f3n, la cual termin\u00f3 a la altura de la colonia Santa Lucia.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-22883 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0037-236x300.jpg\" alt=\"\" width=\"236\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0037-236x300.jpg 236w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0037-806x1024.jpg 806w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0037-768x975.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/IMG-20211013-WA0037.jpg 1008w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/>Al detener la marcha del autom\u00f3vil descendieron dos hombres que iniciaron otra persecuci\u00f3n a pie siendo alcanzados y controlados metros mas adelante por los elementos policiacos.<\/p>\n<p>Tras todo est\u00e9 movimiento, al realizarles una inspecci\u00f3n les fueron localizados entre su ropa unas bolsas con sustancia solida y cristalina con las caracter\u00edsticas de la droga conocida como cristal.<\/p>\n<p>El primer detenido fue identificado como Pablo Martin L. de 32 a\u00f1os, quien al verificar sus datos arroj\u00f3 que cuenta con antecedentes por los delitos de homicidio, robo con violencia y violencia familiar; mientras que el segundo detenido fue identificado como Ra\u00fal L. de 39 a\u00f1os ambos con domicilio en el municipio de monterrey.<\/p>\n<p>Las dos personas y el veh\u00edculo fueron puestos a disposici\u00f3n del Ministerio Publico para que determine su situaci\u00f3n jur\u00eddica, y las autoridades se encuentran trabajando para descartar su participaci\u00f3n en alg\u00fan evento de robo suscitado en la zona.<\/p>\n<p>Fuente: La \u00daltima Palabra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N L.- Fue cerca de las 16:00 horas de hoy mi\u00e9rcoles 13 de octubre que elementos de la Secretaria de Seguridad P\u00fablica de Ju\u00e1rez, recibieron el reporte sobre un veh\u00edculo tipo Mondeo en color arena que circulaba a exceso de velocidad pasandose los sem\u00e1foros en rojo sobre la avenida Eloy Cavazos en direcci\u00f3n al [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":22882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[817,3076],"class_list":["post-22881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-detenciones-juarez","tag-fuente-la-ultima-palabra"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/22881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=22881"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/22881\/revisions"}],"predecessor-version":[{"id":74346,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/22881\/revisions\/74346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/22882"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=22881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=22881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=22881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}