                       {"id":23053,"date":"2021-10-20T18:23:13","date_gmt":"2021-10-21T00:23:13","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=23053"},"modified":"2024-12-11T10:15:50","modified_gmt":"2024-12-11T16:15:50","slug":"carolina-habia-sufrido-agresiones-de-su-pareja","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/carolina-habia-sufrido-agresiones-de-su-pareja\/","title":{"rendered":"Carolina hab\u00eda sufrido agresiones de su pareja"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-23074 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/SSO-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/SSO-300x198.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/10\/SSO.jpg 690w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- Brandon y Carolina se conocieron a mediados de 2016, al coincidir como empleados de un call center en el Parque Industrial La Silla.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ella, entonces de 19 a\u00f1os, hab\u00eda tenido que terminar repentinamente con un anterior novio de la adolescencia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se &#8220;flecharon&#8221;, y a los pocos meses decidieron vivir en uni\u00f3n libre. Naci\u00f3 su primera hija, pero tiempo despu\u00e9s, la conducta del joven marido comenz\u00f3 a cambiar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se torn\u00f3 agresivo y, seg\u00fan personas cercanas a la pareja, constantemente maltrataba a &#8220;Caro&#8221;, al grado de que tambi\u00e9n lleg\u00f3 a golpearla.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Habitaban en la colonia Las Lomas de Ju\u00e1rez, donde los conflictos entre ellos, las separaciones y las reconciliaciones tambi\u00e9n eran frecuentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hay quien dice que Brandon comenz\u00f3 a tener problemas de adicciones apenas a mediados del a\u00f1o pasado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante los \u00faltimos tres meses, el ahora presunto multihomicida de Ju\u00e1rez estuvo internado en un centro de rehabilitaci\u00f3n antiadicciones. En ese tiempo, Carolina vivi\u00f3 con sus dos hijas en la casa de sus padres, en la colonia Santa M\u00f3nica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El s\u00e1bado en la ma\u00f1ana, la madre y el padrastro de Brandon fueron a buscar a su nuera y sus nietas para llevarlas a comer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Enfilaron al domicilio de la colonia Mirador de San Antonio, donde finalmente ocurri\u00f3 la tragedia.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Brandon y Carolina se conocieron a mediados de 2016, al coincidir como empleados de un call center en el Parque Industrial La Silla. Ella, entonces de 19 a\u00f1os, hab\u00eda tenido que terminar repentinamente con un anterior novio de la adolescencia. Se &#8220;flecharon&#8221;, y a los pocos meses decidieron vivir en uni\u00f3n libre. Naci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":23074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[3075,1597],"class_list":["post-23053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-fuente-el-norte","tag-multihomicidio-en-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/23053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=23053"}],"version-history":[{"count":3,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/23053\/revisions"}],"predecessor-version":[{"id":74412,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/23053\/revisions\/74412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/23074"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=23053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=23053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=23053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}