                       {"id":24197,"date":"2021-12-16T15:11:01","date_gmt":"2021-12-16T21:11:01","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=24197"},"modified":"2024-12-11T11:15:54","modified_gmt":"2024-12-11T17:15:54","slug":"aprueban-paquete-de-egresos-2022-para-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/aprueban-paquete-de-egresos-2022-para-juarez\/","title":{"rendered":"Aprueban paquete de Egresos 2022 para Ju\u00e1rez"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-24207 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/12\/IMG-20211216-WA0014-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/12\/IMG-20211216-WA0014-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/12\/IMG-20211216-WA0014-1024x576.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/12\/IMG-20211216-WA0014-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/12\/IMG-20211216-WA0014-1536x864.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2021\/12\/IMG-20211216-WA0014.jpg 1599w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- Poco despu\u00e9s de la s\u00e9ptima sesi\u00f3n ordinaria de cabildo, el alcalde de Ju\u00e1rez, Paco Trevi\u00f1o, inform\u00f3 la aprobaci\u00f3n del presupuesto de 1,024 millones de pesos para el municipio de Ju\u00e1rez.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El edil dijo sentirse alentado por la aprobaci\u00f3n por unanimidad de los ediles en la sesi\u00f3n plenaria, as\u00ed como en la de Comisi\u00f3n de Hacienda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mencion\u00f3 que entre los rubros para aplicar los Egresos del 2022, ser\u00e1 la inversi\u00f3n p\u00fablica, de las cuales algunas obras ya est\u00e1n en proceso como la ampliaci\u00f3n de la carretera a San Mateo, la construcci\u00f3n del C-4 para Seguridad P\u00fablica Municipal, as\u00ed como varias delegaciones de Polic\u00eda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por \u00faltimo agreg\u00f3 que espera que el Congreso del Estado apruebe ese presupuesto tan necesario para el bien de Ju\u00e1rez y sus colonias.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre otros temas, tambi\u00e9n por unanimidad se aprob\u00f3 el plan Municipal de Desarrollo, en la que intervienen todos los rubros de la administraci\u00f3n p\u00fablica.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Poco despu\u00e9s de la s\u00e9ptima sesi\u00f3n ordinaria de cabildo, el alcalde de Ju\u00e1rez, Paco Trevi\u00f1o, inform\u00f3 la aprobaci\u00f3n del presupuesto de 1,024 millones de pesos para el municipio de Ju\u00e1rez. El edil dijo sentirse alentado por la aprobaci\u00f3n por unanimidad de los ediles en la sesi\u00f3n plenaria, as\u00ed como en la de Comisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":24208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3437,3076,1684],"class_list":["post-24197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-egresos-2022-juarez","tag-fuente-la-ultima-palabra","tag-paco-trevino"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/24197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=24197"}],"version-history":[{"count":3,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/24197\/revisions"}],"predecessor-version":[{"id":74853,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/24197\/revisions\/74853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/24208"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=24197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=24197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=24197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}