                       {"id":25216,"date":"2022-02-05T10:20:28","date_gmt":"2022-02-05T16:20:28","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=25216"},"modified":"2024-12-11T11:15:59","modified_gmt":"2024-12-11T17:15:59","slug":"asegura-inm-36-migrantes-en-cadereyta","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/asegura-inm-36-migrantes-en-cadereyta\/","title":{"rendered":"Asegura INM 36 migrantes en Cadereyta"},"content":{"rendered":"<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-25216-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/VID-20220205-WA0003.mp4?_=1\" \/><a href=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/VID-20220205-WA0003.mp4\">https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/VID-20220205-WA0003.mp4<\/a><\/video><\/div>\n<p><span style=\"font-weight: 400;\">Cadereyta Jim\u00e9nez, N.L.- El Instituto Nacional de Migraci\u00f3n (INM) localiz\u00f3 ayer a 36 migrantes indocumentados en un hotel de Cadereyta, siendo casi la mitad menores de edad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En una serie de visitas de verificaci\u00f3n en diversas locaciones del municipio, en coordinaci\u00f3n con la Secretar\u00eda de Seguridad de Cadereyta, personal de la dependencia federal hall\u00f3 a los migrantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se report\u00f3 que 17 de ellos eran menores que no estaban acompa\u00f1ados.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tras ser encontrados en un cateo al Hotel Posada San Lorenzo, en la Colonia L\u00e1zaro C\u00e1rdenas, las autoridades informaron mediante una ficha informativa que los 36 extranjeros fueron trasladados a la estaci\u00f3n migratoria de Guadalupe, tras no acreditar su estancia regular en el Pa\u00eds.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ni las autoridades de Cadereyta ni las de INM precisaron la nacionalidad de los migrantes, al referir \u00fanicamente que al menos los 17 menores eran de origen centroamericano.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- El Instituto Nacional de Migraci\u00f3n (INM) localiz\u00f3 ayer a 36 migrantes indocumentados en un hotel de Cadereyta, siendo casi la mitad menores de edad. En una serie de visitas de verificaci\u00f3n en diversas locaciones del municipio, en coordinaci\u00f3n con la Secretar\u00eda de Seguridad de Cadereyta, personal de la dependencia federal hall\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[3075,3519,2366],"class_list":["post-25216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-fuente-el-norte","tag-inm","tag-migrantes-cadereyta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=25216"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25216\/revisions"}],"predecessor-version":[{"id":75177,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25216\/revisions\/75177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/25219"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=25216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=25216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=25216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}