                       {"id":25252,"date":"2022-02-05T17:10:10","date_gmt":"2022-02-05T23:10:10","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=25252"},"modified":"2024-12-11T11:15:59","modified_gmt":"2024-12-11T17:15:59","slug":"ante-bajas-temperaturas-comparte-blanca-flores-despensas-y-cobertores","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/ante-bajas-temperaturas-comparte-blanca-flores-despensas-y-cobertores\/","title":{"rendered":"Ante bajas temperaturas, comparte Blanca Flores despensas y cobertores"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25250 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220205-WA0018-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220205-WA0018-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220205-WA0018-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220205-WA0018-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220205-WA0018-1536x1152.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220205-WA0018.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cadereyta Jim\u00e9nez, N.L.- Ante la presencia de las bajas temperaturas\u00a0 en el Estado de Nuevo Le\u00f3n; la novena regidora, Blanca Flores y el grupo de amigos Dominados4x4, realizaron la entrega de cobertores y productos b\u00e1sicos de la despensa a familias de la colonia L\u00e1zaro C\u00e1rdenas en el municipio de Cadereyta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fue la noche de ayer viernes 4 de enero con el term\u00f3metro marcando los 2\u00b0C, cuando el grupo de amigos y la regidora se organizaron para recorrer algunos de los hogares m\u00e1s vulnerables\u00a0 para compartir\u00a0 chocolate\u00a0 caliente, cobertores y algunos productos b\u00e1sicos de la despensa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las familias sorprendidas, agradecieron la atenci\u00f3n y desearon lo mejor para que continuar\u00e1n con esa voluntad de apoyar.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- Ante la presencia de las bajas temperaturas\u00a0 en el Estado de Nuevo Le\u00f3n; la novena regidora, Blanca Flores y el grupo de amigos Dominados4x4, realizaron la entrega de cobertores y productos b\u00e1sicos de la despensa a familias de la colonia L\u00e1zaro C\u00e1rdenas en el municipio de Cadereyta. Fue la noche de ayer [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[3524,308,3076],"class_list":["post-25252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-apoyos-ciudadanos","tag-blanca-flores","tag-fuente-la-ultima-palabra"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=25252"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25252\/revisions"}],"predecessor-version":[{"id":75193,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25252\/revisions\/75193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/25249"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=25252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=25252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=25252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}