                       {"id":25600,"date":"2022-02-18T15:54:00","date_gmt":"2022-02-18T21:54:00","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=25600"},"modified":"2024-12-11T11:16:01","modified_gmt":"2024-12-11T17:16:01","slug":"investigan-el-hallazgo-de-presuntos-restos-humanos-en-vistas-del-rio","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/investigan-el-hallazgo-de-presuntos-restos-humanos-en-vistas-del-rio\/","title":{"rendered":"Investigan el hallazgo de presuntos restos humanos en Vistas del R\u00edo\u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25590 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220218-WA0036-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220218-WA0036-300x170.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220218-WA0036-1024x580.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220218-WA0036-768x435.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220218-WA0036-1536x870.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/02\/IMG-20220218-WA0036.jpg 1599w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Juarez, N.L.- Esta tarde en la Avenida Vistas de Concho en la colonia Vistas del R\u00edo se dio una movilizaci\u00f3n por parte de autoridades quienes investigan el hallazgo de lo que podr\u00eda ser restos humanos.<\/p>\n<p>Esto despu\u00e9s de que se encontraron algunos restos \u00f3seos en una bolsa de basura por personal de Servicios P\u00fablicos Municipales, quienes se encontraban haciendo limpieza en un costado de la avenida y hacen el llamado al 911 para reportar este hallazgo, acudiendo elementos de la Polic\u00eda Municipal y del Instituto de Criminalistica y Servicios Periciales para iniciar las correspondientes investigaciones.<\/p>\n<p>Fuente: La \u00daltima Palabra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juarez, N.L.- Esta tarde en la Avenida Vistas de Concho en la colonia Vistas del R\u00edo se dio una movilizaci\u00f3n por parte de autoridades quienes investigan el hallazgo de lo que podr\u00eda ser restos humanos. Esto despu\u00e9s de que se encontraron algunos restos \u00f3seos en una bolsa de basura por personal de Servicios P\u00fablicos Municipales, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[3076,3552],"class_list":["post-25600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-fuente-la-ultima-palabra","tag-restos-oseos-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=25600"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25600\/revisions"}],"predecessor-version":[{"id":75333,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25600\/revisions\/75333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/25585"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=25600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=25600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=25600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}