                       {"id":25977,"date":"2022-03-02T17:19:41","date_gmt":"2022-03-02T23:19:41","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=25977"},"modified":"2024-12-11T11:16:04","modified_gmt":"2024-12-11T17:16:04","slug":"denuncian-robo-de-camaras-en-heroe-de-nacozari","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/denuncian-robo-de-camaras-en-heroe-de-nacozari\/","title":{"rendered":"Denuncian robo de c\u00e1maras en H\u00e9roe de Nacozari"},"content":{"rendered":"<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-25977-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/VID-20220302-WA0053.mp4?_=1\" \/><a href=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/VID-20220302-WA0053.mp4\">https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/VID-20220302-WA0053.mp4<\/a><\/video><\/div>\n<p>Ju\u00e1rez, N.L.- Un sujeto est\u00e1 siendo se\u00f1alado por robar todas las c\u00e1maras de seguridad en la colonia H\u00e9roe de Nacozari en el municipio de Ju\u00e1rez.<\/p>\n<p>Seg\u00fan versiones de los quejosos, el sujeto llega, arranca las c\u00e1maras de seguridad, se pasea y luego va por otras. El ultimo atraco se registr\u00f3 el pasado s\u00e1bado en la madrugada a las 3:45 y a las 5:15 h de la ma\u00f1ana, cuando rob\u00f3 dos c\u00e1maras en uno de los domicilios de esta colonia;\u00a0 y en otros m\u00e1s, los cuales a\u00fan no han puesto denuncia.<\/p>\n<p>Los vecinos sospechan de dos hermanos a los que apodan los \u2018\u2019cheetos\u2019\u2019, y piden que sean investigados por qu\u00e9 se ha reconocido a uno de ellos, por una foto que circula en redes sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un sujeto est\u00e1 siendo se\u00f1alado por robar todas las c\u00e1maras de seguridad en la colonia H\u00e9roe de Nacozari en el municipio de Ju\u00e1rez. Seg\u00fan versiones de los quejosos, el sujeto llega, arranca las c\u00e1maras de seguridad, se pasea y luego va por otras. El ultimo atraco se registr\u00f3 el pasado s\u00e1bado en la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[3258,3076,3631,3590,3630],"class_list":["post-25977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-denuncias-ciudadanas-juarez","tag-fuente-la-ultima-palabra","tag-heroe-de-nacozari","tag-juarez-nl","tag-robo-de-camaras"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=25977"}],"version-history":[{"count":3,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25977\/revisions"}],"predecessor-version":[{"id":75467,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/25977\/revisions\/75467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/25978"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=25977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=25977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=25977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}