                       {"id":26491,"date":"2022-03-18T17:09:30","date_gmt":"2022-03-18T23:09:30","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=26491"},"modified":"2024-12-11T11:16:08","modified_gmt":"2024-12-11T17:16:08","slug":"pide-apoyo-tras-perder-todo-en-incendio","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/pide-apoyo-tras-perder-todo-en-incendio\/","title":{"rendered":"Pide apoyo tras perder todo en incendio"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-26491 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/laultimapalabra.com.mx\/portal\/pide-apoyo-tras-perder-todo-en-incendio\/img-20220318-wa0041\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0041-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/laultimapalabra.com.mx\/portal\/pide-apoyo-tras-perder-todo-en-incendio\/img-20220318-wa0029\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0029-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/laultimapalabra.com.mx\/portal\/pide-apoyo-tras-perder-todo-en-incendio\/img-20220318-wa0043\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0043-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Ju\u00e1rez, N.L.- Tras perder todo su patrimonio en un incendio, la vecina Sara Ang\u00e9lica Mart\u00ednez Vallejo busca el apoyo por parte de la ciudadan\u00eda y del gobierno para as\u00ed poder recuperar un poco de lo que vio perdido en el siniestro.<br \/>\nLa se\u00f1ora Sara sufri\u00f3 la p\u00e9rdida total de sus bienes, ya que su casa marcada con el n\u00famero 1142 ubicado en la calle Saturnino Gonz\u00e1lez en la colonia Colinas del Sol segundo sector en el municipio de Ju\u00e1rez Nuevo Le\u00f3n, fue v\u00edctima de un incendio a causa de un corto circuito el d\u00eda de ayer jueves alrededor de las 19:30 horas.<br \/>\nSi usted desea ayudar puede ponerse en contacto con la se\u00f1ora Sara al tel\u00e9fono 81 10 65 28 80.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Tras perder todo su patrimonio en un incendio, la vecina Sara Ang\u00e9lica Mart\u00ednez Vallejo busca el apoyo por parte de la ciudadan\u00eda y del gobierno para as\u00ed poder recuperar un poco de lo que vio perdido en el siniestro. La se\u00f1ora Sara sufri\u00f3 la p\u00e9rdida total de sus bienes, ya que su casa [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":26493,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3815,3816,3817,3076,1254,3590],"class_list":["post-26491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-apoyo-ciudadano","tag-apoyo-gobierno","tag-colonia-colinas-del-sol","tag-fuente-la-ultima-palabra","tag-incendio","tag-juarez-nl"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/26491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=26491"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/26491\/revisions"}],"predecessor-version":[{"id":75692,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/26491\/revisions\/75692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/26493"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=26491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=26491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=26491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}