                       {"id":26503,"date":"2022-03-18T17:32:56","date_gmt":"2022-03-18T23:32:56","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=26503"},"modified":"2024-12-11T11:16:08","modified_gmt":"2024-12-11T17:16:08","slug":"atenderan-en-juarez-mujeres-embarazadas-en-situacion-vulnerable","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/atenderan-en-juarez-mujeres-embarazadas-en-situacion-vulnerable\/","title":{"rendered":"Atender\u00e1n en Ju\u00e1rez mujeres embarazadas en situacion vulnerable"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-26504 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0046-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0046-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0046-1024x682.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0046-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0046.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Juarez, N.L.- El Municipio de Ju\u00e1rez y la asociaci\u00f3n civil Vifac firmaron un convenio de colaboraci\u00f3n para dar toda la atenci\u00f3n a las mujeres juarenses que se encuentren en una situaci\u00f3n de vulnerabilidad durante un embarazo.<br \/>\nEn el evento, la directora del Vifac mostr\u00f3 su reconocimiento a la Administraci\u00f3n de Ju\u00e1rez al se\u00f1alar que est\u00e1 demostrando con hechos concretos sus proyectos de atenci\u00f3n a las mujeres.<br \/>\nTras la firma del convenio de colaboraci\u00f3n, la asociaci\u00f3n civil trabajar\u00e1 en coordinaci\u00f3n con el DIF y otras dependencias municipales con el prop\u00f3sito de que las mujeres embarazadas y en situaci\u00f3n de abandono tengan alojamiento, alimentaci\u00f3n, atenci\u00f3n m\u00e9dica y atenci\u00f3n psicol\u00f3gica.<br \/>\nTambi\u00e9n tendr\u00e1n capacitaci\u00f3n para que contin\u00faen laborando, o si lo prefieren, instalar un negocio con lo que aprendan en cursos de autoempleo.<br \/>\nEl Municipio de Ju\u00e1rez se\u00f1al\u00f3 que siempre velar\u00e1 por el bien de las mujeres, y prueba de ello es la creaci\u00f3n del programa Mujer No Est\u00e1s Sola, que lo lleva a cabo Prevenci\u00f3n del Delito y el Instituto de la Mujer.<br \/>\nY ahora, tras la firma del convenio con el Vifac, se van a reforzar estas acciones poniendo especial atenci\u00f3n en las mujeres embarazadas que por alguna raz\u00f3n no tienen a alguien que las apoye.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juarez, N.L.- El Municipio de Ju\u00e1rez y la asociaci\u00f3n civil Vifac firmaron un convenio de colaboraci\u00f3n para dar toda la atenci\u00f3n a las mujeres juarenses que se encuentren en una situaci\u00f3n de vulnerabilidad durante un embarazo. En el evento, la directora del Vifac mostr\u00f3 su reconocimiento a la Administraci\u00f3n de Ju\u00e1rez al se\u00f1alar que est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":26505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3822,3076,3823,3590,1684,3821],"class_list":["post-26503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-atencion-a-mujeres","tag-fuente-la-ultima-palabra","tag-gobierno-municipal-de-juarez","tag-juarez-nl","tag-paco-trevino","tag-vifac"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/26503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=26503"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/26503\/revisions"}],"predecessor-version":[{"id":75696,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/26503\/revisions\/75696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/26505"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=26503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=26503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=26503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}