                       {"id":2704,"date":"2018-07-27T00:08:06","date_gmt":"2018-07-27T00:08:06","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=2704"},"modified":"2024-12-11T08:37:22","modified_gmt":"2024-12-11T14:37:22","slug":"intentan-reos-atacar-a-asesino-de-anita","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/intentan-reos-atacar-a-asesino-de-anita\/","title":{"rendered":"Intentan reos atacar a asesino de Anita"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2705 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/07\/reo-300x251.jpg\" alt=\"\" width=\"300\" height=\"251\" \/>Internos del penal del Topo Chico, muestran su repudio contra el presunto homicida y amenazan con linchamiento<\/p>\n<p style=\"text-align: justify;\">CD. BENITO JU\u00c1REZ, N.L.-<br \/>\nCuando era trasladado a una de las \u00e1reas del Topo Chico El presunto asesino y secuestrador de la peque\u00f1a Ana Lizbeth Polina Ram\u00edrez, un grupo de presos intent\u00f3 agredirlo f\u00edsicamente y le profirieron amenazas por la muerte de la peque\u00f1a de la colonia Vistas del R\u00edo de esta ciudad.<br \/>\nIdentificado como Juan Fernando Ruiz ramos, de 37 a\u00f1os de edad, tuvo que ser escoltado por un grupo extremo de custodios ante el temor de linchamiento, por parte de los reos, por el perverso crimen de la ni\u00f1a.<br \/>\nSolo un custodio es el que lleva a los reos a las audiencias con el juez de control, pero esta vez fueron ocho los que custodiaron al hermano de un fiscal de la Procuradur\u00eda.<br \/>\nLos reos se encontraban indignados por el artero crimen y mostraron su repudio en contra del detenido que actualmente se encuentra aislado en el departamento de Observaci\u00f3n ya que se teme por su vida en el interior del penal del Topo Chico.<br \/>\nLa orden para aislarlo fue dada por la juez, quien lo vincul\u00f3 a proceso por feminicidio y secuestro agravado en contra de la peque\u00f1a Anita, quien fue encontrada muerta apenas unos 300 metros de donde fue plagiada por el ex polic\u00eda.<br \/>\nPor otra parte, se ignora a\u00fan si ya se le ejecut\u00f3 una segunda orden de aprehensi\u00f3n por la violaci\u00f3n sexual en contra de una menor de edad ocurrida en septiembre del 2014.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internos del penal del Topo Chico, muestran su repudio contra el presunto homicida y amenazan con linchamiento CD. BENITO JU\u00c1REZ, N.L.- Cuando era trasladado a una de las \u00e1reas del Topo Chico El presunto asesino y secuestrador de la peque\u00f1a Ana Lizbeth Polina Ram\u00edrez, un grupo de presos intent\u00f3 agredirlo f\u00edsicamente y le profirieron amenazas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2705,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[198],"class_list":["post-2704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-asesino-de-anita"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/2704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=2704"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/2704\/revisions"}],"predecessor-version":[{"id":64471,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/2704\/revisions\/64471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=2704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=2704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=2704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}