                       {"id":27068,"date":"2022-04-04T15:24:00","date_gmt":"2022-04-04T21:24:00","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=27068"},"modified":"2024-12-11T11:16:12","modified_gmt":"2024-12-11T17:16:12","slug":"balean-a-joven-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/balean-a-joven-en-juarez\/","title":{"rendered":"Balean a joven en Ju\u00e1rez"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27069 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220404-WA0040-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220404-WA0040-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220404-WA0040.jpg 678w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Juarez, N.L..- Un joven de 20 a\u00f1os fue atacado a balazos, anoche en Ju\u00e1rez.<br \/>\nEl lesionado fue identificado como Omar Israel Castro Balderas, de 20 a\u00f1os.<br \/>\nLas autoridades informaron que el joven recibi\u00f3 el balazo en el abdomen, lo que lo dej\u00f3 gravemente herido.<br \/>\nSin embargo no trascendi\u00f3 la informaci\u00f3n del lugar exacto en el que sucedieron los hechos.<br \/>\nUna fuente cercana a las investigaciones se\u00f1al\u00f3 que unos conocidos de la v\u00edctima lo trasladaron en un auto particular a la delegaci\u00f3n de la Cruz Verde de Guadalupe, en la Colonia Santa Cruz.<br \/>\nLos m\u00e9dicos de guardia estabilizaron al herido y unos param\u00e9dicos particulares lo llevaron grave al Hospital Universitario.<br \/>\nDurante la madrugada se dijo que el herido permanec\u00eda en estado delicado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juarez, N.L..- Un joven de 20 a\u00f1os fue atacado a balazos, anoche en Ju\u00e1rez. El lesionado fue identificado como Omar Israel Castro Balderas, de 20 a\u00f1os. Las autoridades informaron que el joven recibi\u00f3 el balazo en el abdomen, lo que lo dej\u00f3 gravemente herido. Sin embargo no trascendi\u00f3 la informaci\u00f3n del lugar exacto en el [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":27069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[4040,3076,3780,3590],"class_list":["post-27068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-balean-a-hombre","tag-fuente-la-ultima-palabra","tag-herido-de-bala","tag-juarez-nl"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=27068"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27068\/revisions"}],"predecessor-version":[{"id":75944,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27068\/revisions\/75944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/27069"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=27068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=27068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=27068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}