                       {"id":27445,"date":"2022-04-11T18:44:50","date_gmt":"2022-04-12T00:44:50","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=27445"},"modified":"2024-12-11T11:16:14","modified_gmt":"2024-12-11T17:16:14","slug":"detienen-a-hombre-con-auto-con-reporte-de-robo-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/detienen-a-hombre-con-auto-con-reporte-de-robo-en-juarez\/","title":{"rendered":"Cae por circular con placas falsas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27446 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220411-WA0023-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220411-WA0023-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220411-WA0023-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/04\/IMG-20220411-WA0023.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ju\u00e1rez, N.L.- Un sujeto fue detenido a las nueve de la ma\u00f1ana del d\u00eda de hoy, cuando se mont\u00f3 un operativo al ser detectado circulando en un auto con placas ap\u00f3crifas.<br \/>\nVarias unidades de Seguridad P\u00fablica de Ju\u00e1rez fueron alertadas por el C4 en el sentido que se ten\u00eda informaci\u00f3n que un auto Chevrolet Malib\u00fa en color blanco, con placas reportadas como falsas se hab\u00eda visto circulando por la Carretera Ju\u00e1rez &#8211; Apodaca.<br \/>\nLa tripulaci\u00f3n de una de las unidades ubicaron el auto en dicha carretera y avenida Primavera en el ejido Ju\u00e1rez y detuvieron a su conductor quien se identific\u00f3 como Sa\u00fal H de 52 a\u00f1os de edad.<br \/>\nEl tripulante del auto con las placas falsas fue entregado a las autoridades competentes para ahondar las investigaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un sujeto fue detenido a las nueve de la ma\u00f1ana del d\u00eda de hoy, cuando se mont\u00f3 un operativo al ser detectado circulando en un auto con placas ap\u00f3crifas. Varias unidades de Seguridad P\u00fablica de Ju\u00e1rez fueron alertadas por el C4 en el sentido que se ten\u00eda informaci\u00f3n que un auto Chevrolet Malib\u00fa [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":27469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[3865,3578,3076],"class_list":["post-27445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-detenidos-juarez-2022","tag-detienen-a-hombre","tag-fuente-la-ultima-palabra"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=27445"}],"version-history":[{"count":4,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27445\/revisions"}],"predecessor-version":[{"id":76084,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27445\/revisions\/76084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/27469"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=27445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=27445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=27445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}