                       {"id":27854,"date":"2022-04-21T11:19:49","date_gmt":"2022-04-21T17:19:49","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=27854"},"modified":"2024-12-11T11:16:16","modified_gmt":"2024-12-11T17:16:16","slug":"atropellan-a-conductor-de-ruta-urbana","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/atropellan-a-conductor-de-ruta-urbana\/","title":{"rendered":"Atropellan a conductor de ruta urbana"},"content":{"rendered":"<p>Juarez, N L.- Un hombre muri\u00f3 atropellado por una la ruta 150 de Valle del Roble en el municipio de Ju\u00e1rez.<\/p>\n<figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_98663\"  width=\"740\" height=\"416\"  data-origwidth=\"740\" data-origheight=\"416\" src=\"https:\/\/www.youtube.com\/embed\/IO-PVYO-SVI?enablejsapi=1&autoplay=0&cc_load_policy=0&iv_load_policy=1&loop=0&fs=1&playsinline=0&controls=1&disablekb=0&color=red&cc_lang_pref=es&rel=0&autohide=2&theme=dark&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div><\/div><\/figure>\n<p>Fue a la altura del kil\u00f3metro 23.5 de la carretera Libre a Reynosa a la altura de la colonia San Antonio.<\/p>\n<p>El hombre el cual llevaba un garrafon de agua en un diablito, qued\u00f3 debajo de la pesada unidad, presuntamente un descuido por parte del conductor fue lo que ocasiono el atropello de su compa\u00f1ero.<\/p>\n<p>El hombre era conocido como &#8220;Don Fili&#8221; quien trabajaba como operador en la misma ruta 150.<\/p>\n<p>Al lugar acudieron elementos de Tr\u00e1nsito Municipal para abanderar la zona, donde se hicieron largas filas en ambos sentidos, en espera del arribo de Servicios Periciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juarez, N L.- Un hombre muri\u00f3 atropellado por una la ruta 150 de Valle del Roble en el municipio de Ju\u00e1rez. Fue a la altura del kil\u00f3metro 23.5 de la carretera Libre a Reynosa a la altura de la colonia San Antonio. El hombre el cual llevaba un garrafon de agua en un diablito, qued\u00f3 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":27855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[4196],"class_list":["post-27854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-accidente"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=27854"}],"version-history":[{"count":5,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27854\/revisions"}],"predecessor-version":[{"id":76212,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/27854\/revisions\/76212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/27855"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=27854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=27854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=27854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}