                       {"id":28078,"date":"2022-04-25T19:07:05","date_gmt":"2022-04-26T01:07:05","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28078"},"modified":"2024-12-11T11:16:17","modified_gmt":"2024-12-11T17:16:17","slug":"28078-2","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/28078-2\/","title":{"rendered":"ATACA A PERRO A MACHETAZOS"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.-Luego de enterarse a trav\u00e9s de las redes sociales de que un hombre agredi\u00f3 a machetazos a un perro en la Colonia 16 de Septiembre, elementos de la Secretar\u00eda de Seguridad P\u00fablica de Ju\u00e1rez realizaron la detenci\u00f3n del agresor y lo pusieron a disposici\u00f3n del Ministerio P\u00fablico.<br \/>\nDe acuerdo con la versi\u00f3n del detenido, reaccion\u00f3 de esa manera porque el perro se encontraba mordiendo a su hermana menor de edad.<br \/>\n&#8220;Derivado de los hechos se\u00f1alados en redes sociales el d\u00eda 24 de abril de 2022, en donde una persona le da machetazos a un perro, es importante dar de conocimiento a los ciudadanos que la persona presuntamente responsable, quien se identific\u00f3 como Jes\u00fas M., de 23 a\u00f1os, se encuentra detenida en las celdas de la Secretar\u00eda de Seguridad P\u00fablica, Vialidad y Tr\u00e1nsito de nuestro municipio&#8221;, inform\u00f3 la Polic\u00eda de Ju\u00e1rez a trav\u00e9s de un comunicado.<br \/>\n&#8220;Se levant\u00f3 un Informe Policial Homologado (IPH) por haber cometido actos de maltrato o crueldad animal, delito tipificado en el art\u00edculo 445 del C\u00f3digo Penal para el Estado de Nuevo Le\u00f3n. El IPH ser\u00e1 remitido al Agente del Ministerio P\u00fablico en turno, quien ser\u00e1 la autoridad encargada de investigar los hechos.<br \/>\n&#8220;El presunto responsable mencion\u00f3 que reaccion\u00f3 de esa manera porque el perro estaba mordiendo a su hermana menor de edad en la pierna derecha&#8221;, finaliz\u00f3 el comunicado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Luego de enterarse a trav\u00e9s de las redes sociales de que un hombre agredi\u00f3 a machetazos a un perro en la Colonia 16 de Septiembre, elementos de la Secretar\u00eda de Seguridad P\u00fablica de Ju\u00e1rez realizaron la detenci\u00f3n del agresor y lo pusieron a disposici\u00f3n del Ministerio P\u00fablico. De acuerdo con la versi\u00f3n del detenido, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[4231,819],"class_list":["post-28078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-ataca-a-perro","tag-detenido"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28078"}],"version-history":[{"count":3,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28078\/revisions"}],"predecessor-version":[{"id":76276,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28078\/revisions\/76276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28079"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}