                       {"id":28401,"date":"2022-05-03T19:49:44","date_gmt":"2022-05-04T01:49:44","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28401"},"modified":"2024-12-11T11:16:18","modified_gmt":"2024-12-11T17:16:18","slug":"capturan-a-dos-por-robar-cables-de-telefonia","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/capturan-a-dos-por-robar-cables-de-telefonia\/","title":{"rendered":"Capturan a dos por robar cables de telefon\u00eda"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-28403 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220503-WA0068-223x300.jpg\" alt=\"\" width=\"223\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220503-WA0068-223x300.jpg 223w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220503-WA0068-761x1024.jpg 761w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220503-WA0068-768x1033.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220503-WA0068.jpg 1050w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/>Ju\u00e1rez, N.L.-<\/span><span style=\"font-size: 1rem;\">Cuando se encontraban en labor de patrullaje, oficiales de Seguridad P\u00fablica de Ju\u00e1rez, detuvieron a dos individuos cuando robaban cable de telefon\u00eda en postes de la colonia Real de San Jos\u00e9.<\/span><\/p>\n<p>Los hechos ocurrieran a las 2:00 horas de ayer lunes, cuando los polic\u00edas observaron la ilegal acci\u00f3n en la avenida Te\u00f3filo Salinas.<br \/>\nEn el lugar fueron detenidos Jos\u00e9 C. de 48 a\u00f1os y Francisco C. de 23 a\u00f1os, quienes tra\u00edan el producto del hurto en una mochila, cable que fue reconocido por un ejecutivo de la empresa afectada.<br \/>\nAmbos detenidos fueron consignados a las autoridades correspondientes para ser investigados por denuncias de tubos similares en esa \u00e1rea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Cuando se encontraban en labor de patrullaje, oficiales de Seguridad P\u00fablica de Ju\u00e1rez, detuvieron a dos individuos cuando robaban cable de telefon\u00eda en postes de la colonia Real de San Jos\u00e9. Los hechos ocurrieran a las 2:00 horas de ayer lunes, cuando los polic\u00edas observaron la ilegal acci\u00f3n en la avenida Te\u00f3filo Salinas. En [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[4264,1355,2016],"class_list":["post-28401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-cable","tag-juarez","tag-robo"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28401"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28401\/revisions"}],"predecessor-version":[{"id":76406,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28401\/revisions\/76406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28402"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}