                       {"id":28461,"date":"2022-05-04T21:54:14","date_gmt":"2022-05-05T03:54:14","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28461"},"modified":"2024-12-11T11:16:18","modified_gmt":"2024-12-11T17:16:18","slug":"llevaba-en-pedazos-auto-con-reporte-de-robo","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/llevaba-en-pedazos-auto-con-reporte-de-robo\/","title":{"rendered":"Llevaba en pedazos, auto con reporte de robo"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.<br \/>\nUn sujeto es investigado al ser sorprendido con pedazos de metal, pertenecientes a un auto con reporte de robo.<br \/>\nLos hechos ocurrieron el d\u00eda de hoy cuatro de mayo a las 16:00 horas, en la calle Desierto de Ordos en la colonia Praderas de Oriente, cuando oficiales de Seguridad P\u00fablica, se percataron que un hombre caminaba cargando pedazos de metal y al ver a los uniformados se puso nervioso y emprendi\u00f3 la huida.<br \/>\nLos polic\u00edas lo detuvieron r\u00e1pidamente y al revisar las partes, una de ellas tra\u00eda el n\u00famero de serie del auto y al revisarlo con la base de datos, result\u00f3 con reporte de robo.<br \/>\nJose G. de 27 a\u00f1os de edad, fue puesto a disposici\u00f3n de las autoridades competentes para ser investigado por varios delitos similares en Ju\u00e1rez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L. Un sujeto es investigado al ser sorprendido con pedazos de metal, pertenecientes a un auto con reporte de robo. Los hechos ocurrieron el d\u00eda de hoy cuatro de mayo a las 16:00 horas, en la calle Desierto de Ordos en la colonia Praderas de Oriente, cuando oficiales de Seguridad P\u00fablica, se percataron que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[1355,2016,4274],"class_list":["post-28461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-juarez","tag-robo","tag-vehiculo"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28461"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28461\/revisions"}],"predecessor-version":[{"id":76434,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28461\/revisions\/76434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28462"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}