                       {"id":28497,"date":"2022-05-06T02:01:07","date_gmt":"2022-05-06T08:01:07","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28497"},"modified":"2024-12-11T11:16:19","modified_gmt":"2024-12-11T17:16:19","slug":"atacan-a-balazos-a-hombre-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/atacan-a-balazos-a-hombre-en-juarez\/","title":{"rendered":"Atacan a balazos a hombre en Ju\u00e1rez"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\">Ju\u00e1rez, N.L.-Un hombre recibi\u00f3 al menos 2 impactos de bala esto despu\u00e9s de ser atacado a balazos en la colonia Vistas del R\u00edo en Ju\u00e1rez<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-28498\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/Picsart_22-05-06_02-56-11-795-300x167.jpg\" alt=\"\" width=\"300\" height=\"167\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/Picsart_22-05-06_02-56-11-795-300x167.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/Picsart_22-05-06_02-56-11-795-1024x569.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/Picsart_22-05-06_02-56-11-795-768x427.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/Picsart_22-05-06_02-56-11-795-1536x853.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/Picsart_22-05-06_02-56-11-795-2048x1138.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Los hechos se suscitaron alrededor de las 4:00 de la tarde de este jueves en la calle Circuito Vista del Puente de la colonia ya mencionada, donde hombres armados presuntamente en una motocicleta de color blanco, llegaron y abrieron fuego en al menos 4 ocasiones contra un hombre que se encontraba afuera de un domicilio.<\/p>\n<p>El hombre identificado como Juan Ramirez de 31 a\u00f1os de edad, recibi\u00f3 dos impactos uno en el pecho y otro en la mano; por lo que fue trasladado por Param\u00e9dicos de Protecci\u00f3n Civil de Ju\u00e1rez al Hospital Universitario.<\/p>\n<p>Al lugar acudieron elementos de la Polic\u00eda Municipal y elementos de la Agencia Estatal de Investigaciones, quienes iniciaron las indagatorias correspondientes.<\/p>\n<figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_84452\"  width=\"740\" height=\"416\"  data-origwidth=\"740\" data-origheight=\"416\" src=\"https:\/\/www.youtube.com\/embed\/NjborAv-Esk?enablejsapi=1&autoplay=0&cc_load_policy=0&iv_load_policy=1&loop=0&fs=1&playsinline=0&controls=1&disablekb=0&color=red&cc_lang_pref=es&rel=0&autohide=2&theme=dark&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div><\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Un hombre recibi\u00f3 al menos 2 impactos de bala esto despu\u00e9s de ser atacado a balazos en la colonia Vistas del R\u00edo en Ju\u00e1rez Los hechos se suscitaron alrededor de las 4:00 de la tarde de este jueves en la calle Circuito Vista del Puente de la colonia ya mencionada, donde hombres armados presuntamente [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[267,1191,1355],"class_list":["post-28497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-baleado","tag-herido","tag-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28497"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28497\/revisions"}],"predecessor-version":[{"id":76450,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28497\/revisions\/76450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28499"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}