                       {"id":28501,"date":"2022-05-06T14:42:45","date_gmt":"2022-05-06T20:42:45","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28501"},"modified":"2024-12-11T11:16:19","modified_gmt":"2024-12-11T17:16:19","slug":"cae-pistolero-en-los-puertos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/cae-pistolero-en-los-puertos\/","title":{"rendered":"Cae pistolero en Los Puertos"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.<\/p>\n<p>Un sujeto fue detenido la noche de ayer por la polic\u00eda de Ju\u00e1rez, Nuevo Le\u00f3n, luego de ser reportado por traer un arma de fuego.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-28503\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220506-WA0041-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220506-WA0041-225x300.jpg 225w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220506-WA0041.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>Los hechos ocurrieron cuando los elementos de Seguridad P\u00fablica, alertados por el C4 que les notific\u00f3 un reporte de una persona armada en la calle Niza de la colonia Los Puertos, hasta donde se dirigieron a investigar.<\/p>\n<p>En el cruce de Niza y Cervera de la mencionada colonia, visualizaron a un sujeto quien al notar la presencia polic\u00edaca, ech\u00f3 a correr, pero fue alcanzado.<\/p>\n<p>Al ser revisado a quien dijo llamarse Walter P. de 26 a\u00f1os de edad, le fue encontrada una pistola escuadra calibre. 25.<\/p>\n<p>El arma y el detenido fueron consignados al CODE, donde investigar\u00e1n al detenido para descartar su participaci\u00f3n en varios hechos delictivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L. Un sujeto fue detenido la noche de ayer por la polic\u00eda de Ju\u00e1rez, Nuevo Le\u00f3n, luego de ser reportado por traer un arma de fuego. Los hechos ocurrieron cuando los elementos de Seguridad P\u00fablica, alertados por el C4 que les notific\u00f3 un reporte de una persona armada en la calle Niza de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":28502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[4279],"class_list":["post-28501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-peligroso"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28501"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28501\/revisions"}],"predecessor-version":[{"id":76452,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28501\/revisions\/76452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28502"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}