                       {"id":28593,"date":"2022-05-09T14:39:03","date_gmt":"2022-05-09T20:39:03","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28593"},"modified":"2024-12-11T11:16:19","modified_gmt":"2024-12-11T17:16:19","slug":"motin-en-carcel-de-ecuador-deja-mas-de-40-muertos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/motin-en-carcel-de-ecuador-deja-mas-de-40-muertos\/","title":{"rendered":"MOT\u00cdN EN C\u00c1RCEL DE ECUADOR DEJA M\u00c1S DE 40 MUERTOS"},"content":{"rendered":"<p>Ap y AFP<br \/>\nQuito. 9 de mayo 2022. Un mot\u00edn en una prisi\u00f3n en el centro de Ecuador dej\u00f3 al menos 43 presos fallecidos, inform\u00f3 este lunes la Fiscal\u00eda, en un nuevo hecho de violencia carcelaria en el pa\u00eds azotado por el aumento sin freno del narcotr\u00e1fico y la criminalidad.<br \/>\n&#8220;Hasta el momento se cuentan 43 internos fallecidos&#8221;, indic\u00f3 la Fiscal\u00eda en Twitter, se\u00f1alando que la informaci\u00f3n est\u00e1 &#8220;en desarrollo&#8221;. El ministro del Interior, Patricio Carrillo, dijo en rueda de prensa que el saldo de fallecidos era de 41.<br \/>\nEl ministro del Interior, Patricio Carrillo, dijo a periodistas que \u201cse ha evacuado a cinco personas (heridas) que est\u00e1n siendo atendidas en el dispensario de salud y dos personas han sido reportadas como fallecidas y han ingresado al Departamento de Medicina Forense\u201d.<br \/>\nA\u00f1adi\u00f3 que \u201cestamos controlando para contener y que no se desate violencia en el resto de los centros (penitenciarios)\u201d.<br \/>\nEn su cuenta de Twitter el Ministerio de Interior hab\u00eda publicado m\u00e1s temprano que el mot\u00edn estaba activo desde \u201cla madrugada de hoy en el Centro de Rehabilitaci\u00f3n Social de Santo Domingo de los Ts\u00e1chilas\u201d.<br \/>\nLa polic\u00eda ha llegado al lugar para buscar el control de esa prisi\u00f3n, ubicada a 70 kil\u00f3metros al suroeste de la capital.<br \/>\nV\u00eddeos que circulan en redes sociales muestran la c\u00e1rcel, a\u00fan a oscuras, y se escuchan gritos y disparos.<br \/>\nEl general Fausto Salinas, que durante las pr\u00f3ximas horas ser\u00e1 posesionado comandante general de la polic\u00eda, dijo a la estaci\u00f3n de televisi\u00f3n Teleamazonas que \u201chay 40 personas recapturadas, presos que trataron de evadir, estamos juntando todos los equipos t\u00e1cticos\u2026 para intervenir en forma inmediata y restablecer el orden en ese centro&#8221;.<br \/>\nocurrido en septiembre con un saldo de 119 fallecidos. Las masacres fueron producto de enfrentamientos entre bandas de narcotr\u00e1fico rivales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap y AFP Quito. 9 de mayo 2022. Un mot\u00edn en una prisi\u00f3n en el centro de Ecuador dej\u00f3 al menos 43 presos fallecidos, inform\u00f3 este lunes la Fiscal\u00eda, en un nuevo hecho de violencia carcelaria en el pa\u00eds azotado por el aumento sin freno del narcotr\u00e1fico y la criminalidad. &#8220;Hasta el momento se cuentan [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":28594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[4289,1568],"class_list":["post-28593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-motin","tag-motines"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28593"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28593\/revisions"}],"predecessor-version":[{"id":76490,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28593\/revisions\/76490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28594"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}