                       {"id":28938,"date":"2022-05-18T13:46:24","date_gmt":"2022-05-18T19:46:24","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=28938"},"modified":"2024-12-11T11:16:21","modified_gmt":"2024-12-11T17:16:21","slug":"detienen-vecinos-a-presunto-acosador","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/detienen-vecinos-a-presunto-acosador\/","title":{"rendered":"Detienen vecinos a  presunto acosador"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.<\/p>\n<p>Vecinos de la colonia Hacienda San Jos\u00e9, detuvieron a un hombre a quien se\u00f1alan como quien acosa a algunas mujeres de la colonia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-28940\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0109-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0109-169x300.jpg 169w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0109-576x1024.jpg 576w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0109.jpg 720w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/p>\n<p>Los hechos ocurrieron anoche en las calles de dicho fraccionamiento, donde detuvieron al sujeto, quien no dio su identidad ni sus generales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-28941\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0110-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0110-225x300.jpg 225w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0110-768x1024.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0110-1152x1536.jpg 1152w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/IMG-20220518-WA0110.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>Los mismos encolerizados vecinos llevaron al detenido a las oficinas de Seguridad P\u00fablica, sin embargo no pudo ser consignado, porque no fue detenido en flagrancia, ni fue detenido por la polic\u00eda municipal, por lo que s\u00f3lo le iban a dar s\u00f3lo algunas horas de arresto.<\/p>\n<p>Sin embargo, trascendi\u00f3 que una de las v\u00edctimas si interpondr\u00e1 una denuncia en contra del sujeto, de quien sus generales ya est\u00e1 en poden de la polic\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L. Vecinos de la colonia Hacienda San Jos\u00e9, detuvieron a un hombre a quien se\u00f1alan como quien acosa a algunas mujeres de la colonia. Los hechos ocurrieron anoche en las calles de dicho fraccionamiento, donde detuvieron al sujeto, quien no dio su identidad ni sus generales. Los mismos encolerizados vecinos llevaron al detenido a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":28943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[52],"class_list":["post-28938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-acosador"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=28938"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28938\/revisions"}],"predecessor-version":[{"id":76620,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/28938\/revisions\/76620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/28943"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=28938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=28938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=28938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}