                       {"id":29017,"date":"2022-05-20T18:13:04","date_gmt":"2022-05-21T00:13:04","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=29017"},"modified":"2024-12-11T10:35:45","modified_gmt":"2024-12-11T16:35:45","slug":"encuentran-cuerpo-embolsado-en-las-aguilas","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/encuentran-cuerpo-embolsado-en-las-aguilas\/","title":{"rendered":"Encuentran cuerpo &#8220;embolsado&#8221; en Las \u00c1guilas"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.- Fue ayer en la tarde cuando se report\u00f3 el hallazgo de un cuerpo encontrado en una brecha a un lado del puente Las \u00c1guilas, el cual estaba envuelto en bolsas de pl\u00e1stico y un tapete, esto entre las colonias Colinas del Sol y Las \u00c1guilas en el municipio de Ju\u00e1rez.<\/p>\n<p>Elementos de Protecci\u00f3n Civil Municipal fueron los primeros en reportar que se trataba de un cuerpo, y aunque de manera oficial no se inform\u00f3 el g\u00e9nero del cuerpo, trascendi\u00f3 que se le observaban zapatos masculinos pero esto fue extra oficial.<\/p>\n<p>Siendo elementos de Criminalistica y Asuntos Periciales, detectives de la Agencia Estatal de Investigaciones y la Polic\u00eda Municipal quienes se hicieron cargo de las primeras investigaciones del cuerpo del que se cree ya ten\u00eda d\u00edas de haber fallecido por su avanzado estado en descomposici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Fue ayer en la tarde cuando se report\u00f3 el hallazgo de un cuerpo encontrado en una brecha a un lado del puente Las \u00c1guilas, el cual estaba envuelto en bolsas de pl\u00e1stico y un tapete, esto entre las colonias Colinas del Sol y Las \u00c1guilas en el municipio de Ju\u00e1rez. Elementos de Protecci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":29018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-29017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=29017"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29017\/revisions"}],"predecessor-version":[{"id":76661,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29017\/revisions\/76661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/29018"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=29017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=29017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=29017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}