                       {"id":29149,"date":"2022-05-25T07:20:00","date_gmt":"2022-05-25T13:20:00","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=29149"},"modified":"2024-12-11T10:35:46","modified_gmt":"2024-12-11T16:35:46","slug":"exigen-investigar-a-quienes-vieron-por-ultima-vez-a-victima","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/exigen-investigar-a-quienes-vieron-por-ultima-vez-a-victima\/","title":{"rendered":"Exigen investigar a quienes vieron por \u00faltima vez a v\u00edctima"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\">Ju\u00e1rez N.L.-<\/span><span style=\"font-size: 1rem;\">La familia de Jose \u00c1ngel Villa Mart\u00ednez, quien fuera encontrado muerto en un bald\u00edo de la colonia Paseo Santa Fe, exigen a las autoridades se investigue a una familia con la que se presume estuvo por \u00faltima vez.<\/span><\/p>\n<div style=\"width: 740px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-29149-1\" width=\"740\" height=\"419\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/VIDEO_a60ba679-f1bb-49f3-bc87-cd5f945d8983.mp4?_=1\" \/><a href=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/VIDEO_a60ba679-f1bb-49f3-bc87-cd5f945d8983.mp4\">https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/05\/VIDEO_a60ba679-f1bb-49f3-bc87-cd5f945d8983.mp4<\/a><\/video><\/div>\n<p>Mencionan que Villa Martinez fue captado cuando abord\u00f3 un auto en el que viajaban dos hombres y una mujer al parecer suegra y yernos el 22 de mayo, fecha de su desaparici\u00f3n.<\/p>\n<p>Trascendi\u00f3 que con la v\u00edctima abordo, llegaron a un domicilio de un hermano del ahora occiso en la Infonavit Benito Ju\u00e1rez, de donde despu\u00e9s partieron a la colonia Paseo de Santa Fe, de donde ya nada se supo hasta que uno de los mismos que viajaban en el auto llev\u00f3 a los familiares hasta donde se encontraba Jos\u00e9 \u00c1ngel sin vida y con huellas de violencia en el rostro y la garganta totalmente destrozada.<\/p>\n<p>Los familiares exigen justicia a la fiscal\u00eda para que la muerte no quede impune y se ahonde en las investigaciones con las \u00faltimas personas con las que estuvo antes de ser encontrado sin vida dos d\u00edas despu\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez N.L.-La familia de Jose \u00c1ngel Villa Mart\u00ednez, quien fuera encontrado muerto en un bald\u00edo de la colonia Paseo Santa Fe, exigen a las autoridades se investigue a una familia con la que se presume estuvo por \u00faltima vez. Mencionan que Villa Martinez fue captado cuando abord\u00f3 un auto en el que viajaban dos hombres [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":29150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[4350,4273,1355],"class_list":["post-29149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-asesinado","tag-desaparecido","tag-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=29149"}],"version-history":[{"count":4,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29149\/revisions"}],"predecessor-version":[{"id":76721,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29149\/revisions\/76721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/29150"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=29149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=29149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=29149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}