                       {"id":29978,"date":"2022-06-20T12:35:24","date_gmt":"2022-06-20T18:35:24","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=29978"},"modified":"2024-12-11T10:35:53","modified_gmt":"2024-12-11T16:35:53","slug":"muere-mujer-en-choque-frontal-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/muere-mujer-en-choque-frontal-en-juarez\/","title":{"rendered":"Muere mujer en choque frontal en Ju\u00e1rez"},"content":{"rendered":"<p>Un choque frontal dej\u00f3 como saldo, una mujer sin vida y un hombre lesionado en el municipio de Ju\u00e1rez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29980\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0024-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0024-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0024-1024x576.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0024-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0024-1536x864.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0024.jpg 1599w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El percance se di\u00f3 la noche del domingo en la carretera a San Mateo en kil\u00f3metro 7.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29981\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0022-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0022-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0022-1024x576.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0022-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0022-1536x864.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/06\/IMG-20220620-WA0022.jpg 1599w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Una camioneta Colorado en color guindo, choc\u00f3 de frente contra un autom\u00f3vil toyota del mismo color, una mujer que viajaba en el auto perdi\u00f3 la vida mientras otro hombre result\u00f3 lesionado, los tripulantes de la camioneta resultaron ilesos.<\/p>\n<p>&nbsp;<\/p>\n<p>El autom\u00f3vil qued\u00f3 en un arroyo debido al fuerte impacto, hasta el momento no se tiene la identidad de la mujer, sin embargo las placas de circulaci\u00f3n que portaba el auto, son FCJ 672A del estado de Coahuila.<\/p>\n<p>&nbsp;<\/p>\n<p>Al lugar acudieron Param\u00e9dicos de Protecci\u00f3n Civil de Ju\u00e1rez, quienes atendieron y lo trasladaron a un hospital, tambi\u00e9n se di\u00f3 fluidez a la vialidad por parte de elementos de Vialidad y Tr\u00e1nsito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un choque frontal dej\u00f3 como saldo, una mujer sin vida y un hombre lesionado en el municipio de Ju\u00e1rez. El percance se di\u00f3 la noche del domingo en la carretera a San Mateo en kil\u00f3metro 7. Una camioneta Colorado en color guindo, choc\u00f3 de frente contra un autom\u00f3vil toyota del mismo color, una mujer que [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":29979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[4196],"class_list":["post-29978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-accidente"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=29978"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29978\/revisions"}],"predecessor-version":[{"id":77099,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/29978\/revisions\/77099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/29979"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=29978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=29978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=29978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}