                       {"id":31136,"date":"2022-07-28T13:01:09","date_gmt":"2022-07-28T19:01:09","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=31136"},"modified":"2024-12-11T10:36:05","modified_gmt":"2024-12-11T16:36:05","slug":"amenaza-kim-con-usar-armas-nucleares-contra-eu-y-surcorea","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/amenaza-kim-con-usar-armas-nucleares-contra-eu-y-surcorea\/","title":{"rendered":"Amenaza kim con usar armas nucleares contra EU y Surcorea"},"content":{"rendered":"<p>Se\u00fal, Corea del Sur.- El l\u00edder de Corea del Norte, Kim Jong Un, advirti\u00f3 que est\u00e1 dispuesto a usar sus armas nucleares en potenciales conflictos militares con Estados Unidos y Corea del Sur, report\u00f3 el jueves la prensa estatal, en un enf\u00e1tico discurso contra sus rivales que dice est\u00e1n poniendo a la pen\u00ednsula de Corea al borde de la guerra.<\/p>\n<p>El discurso de Kim ante veteranos en el 69no aniversario del fin de la Guerra de Corea, que se llev\u00f3 a cabo de 1950 a 1953, fue con el objetivo aparente de impulsar la unidad interna en la empobrecida naci\u00f3n, que atraviesa dificultades econ\u00f3micas relacionadas con la pandemia de covid-19. Aunque el mandatario ha intensificado sus amenazas nucleares contra Washington y Se\u00fal, es poco probable que las emplee primero dada la superioridad de ambos ej\u00e9rcitos, seg\u00fan los expertos.<\/p>\n<p>Kim dijo tambi\u00e9n que el nuevo gobierno del presidente surcoreano Yoon Suk Yeol est\u00e1 dirigido por \u201cman\u00edacos de la confrontaci\u00f3n\u201d y \u201cmafiosos&#8221; que han ido m\u00e1s lejos que los anteriores ejecutivos conservadores de la naci\u00f3n. Desde que asumi\u00f3 el poder en mayo, el gobierno de Yoon ha tomado medidas para fortalecer la alianza militar de Se\u00fal con Estados Unidos y reforzar su capacidad para neutralizar las amenazas nucleares de Corea del Norte, incluyendo una capacidad de ataque preventivo.<\/p>\n<p>Moon Hong-sik, portavoz adjunto del Ministerio de Defensa surcoreano, reiter\u00f3 el jueves la postura previa de Se\u00fal, que ha estado reforzando su capacidad militar y las posturas de defensa conjunta con Washington para hacer frente a la escalada de las amenazas nucleares del Norte. El jefe del Estado Mayor del pa\u00eds dijo que el ej\u00e9rcito mantiene una firme preparaci\u00f3n.<\/p>\n<p>Las fuerzas de Kim han probado tambi\u00e9n misiles con capacidad nuclear que podr\u00edan alcanzar tanto el territorio continental estadounidense como Corea del Sur. En los \u00faltimos meses, funcionarios de ambas naciones han repetido que Pyongyang est\u00e1 lista para llevar a cabo su primera prueba nuclear en cinco a\u00f1os.<\/p>\n<p>Seg\u00fan algunos expertos, el Norte podr\u00eda intensificar sus amenazas contra Estados Unidos y Corea del Sur en un momento en que ambos aliados se alistan para unas amplias maniobras militares estivales, que el gobierno norcoreano considera un ensayo de invasi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se\u00fal, Corea del Sur.- El l\u00edder de Corea del Norte, Kim Jong Un, advirti\u00f3 que est\u00e1 dispuesto a usar sus armas nucleares en potenciales conflictos militares con Estados Unidos y Corea del Sur, report\u00f3 el jueves la prensa estatal, en un enf\u00e1tico discurso contra sus rivales que dice est\u00e1n poniendo a la pen\u00ednsula de Corea [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":31137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[3896],"class_list":["post-31136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-fuente-la-jornada"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/31136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=31136"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/31136\/revisions"}],"predecessor-version":[{"id":77635,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/31136\/revisions\/77635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/31137"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=31136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=31136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=31136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}