                       {"id":3151,"date":"2018-08-24T01:31:05","date_gmt":"2018-08-24T01:31:05","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=3151"},"modified":"2024-12-11T08:37:26","modified_gmt":"2024-12-11T14:37:26","slug":"tumban-policias-mandos-de-seguridad-publica","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/tumban-policias-mandos-de-seguridad-publica\/","title":{"rendered":"Tumban polic\u00edas mandos de Seguridad P\u00fablica"},"content":{"rendered":"<p style=\"text-align: justify;\">*Destituyen a director y coordinadores y pide licencia secretario por paro de labores de 90 polic\u00edas<\/p>\n<p style=\"text-align: justify;\">Miguel Oscar P\u00e9rez<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3152 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/08\/DSCN0165-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>CD. BENITO JU\u00c1REZ, N.L.-<br \/>\nA las ocho de la ma\u00f1ana del pasado martes 21 de agosto, estall\u00f3 un paro de labores por la guardia entrante de esa ma\u00f1ana, que al final deton\u00f3 con la salida del teniente coronel Teodoro Jaimes Mart\u00ednez, por medio de una licencia y la destituci\u00f3n del Director de la corporaci\u00f3n, Luis Fernando Mu\u00f1oz y otros mandos medios.<br \/>\nMinutos despu\u00e9s que iniciara el paro, al lugar arrib\u00f3 Julio Cant\u00fa, contralor y encargado del despacho del alcalde para tratar de dialogar con los inconformes que se\u00f1alaban al secretario y sus cercanos colaboradores de trato indigno para ellos.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3153 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/08\/DSCN0185-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>Entre los se\u00f1alamientos dec\u00edan que por cualquier motivo, por m\u00e1s peque\u00f1o que fuera, los efectivos eran dados de baja sin haber de por medio una investigaci\u00f3n de los hechos.<br \/>\nDenunciaron que en el lugar hab\u00eda una tienda que ellos llamaban \u201ccasino\u201d, propiedad del secretario con licencia en donde eran obligados a consumir forzosamente en ese lugar.<br \/>\nMencionaron que las reparaciones de las unidades corr\u00edan a cargo de los polic\u00edas, en forma obligada pagando de sus bolsillos reparaciones de llantas entre otras cosas, mostrando recibos de una vulcanizadora, entre varias denuncias.<br \/>\nEl contralor les invitaba a denunciar los hechos para poder iniciar un procedimiento a los funcionarios se\u00f1alados, pero los polic\u00edas manten\u00edan su postura de no trabajar hasta que no se destituyera al secretario, director y colaboradores.<br \/>\nLos polic\u00edas hicieron una marcha de ida y vuelta de Seguridad P\u00fablica al Palacio Municipal, mientras el encargado del despacho daba una conferencia de prensa.<br \/>\nAl llegar la tarde, se formaron comisiones de Contralor\u00eda, Ejecutiva, secretar\u00eda del Ayuntamiento y Recursos Humanos para dialogar con los inconformes y llegando al acuerdo de la destituci\u00f3n de mandos medios y el director, mientras se les informaba que el secretario hab\u00eda solicitado su licencia para ser investigado.<br \/>\nLos uniformados de inmediato se pusieron a laborar en las unidades al cumplirse la mayor\u00eda de sus peticiones, pero en punto de la media noche volvieron a parar al arribar el secretario escoltado por militares a la secretar\u00eda, pero el paro solo fue moment\u00e1neo al comprobar que el funcionario con licencia solo fue a sus oficinas por sus cosas personales.<br \/>\nAl cierre de esta edici\u00f3n los oficiales ya sin los mandos que se\u00f1alaron, se encontraban laborando normalmente quedando el director de tr\u00e1nsito como encargado del despacho de la secretar\u00eda de Seguridad P\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Destituyen a director y coordinadores y pide licencia secretario por paro de labores de 90 polic\u00edas Miguel Oscar P\u00e9rez CD. BENITO JU\u00c1REZ, N.L.- A las ocho de la ma\u00f1ana del pasado martes 21 de agosto, estall\u00f3 un paro de labores por la guardia entrante de esa ma\u00f1ana, que al final deton\u00f3 con la salida del [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3154,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7,8,10],"tags":[808,1366],"class_list":["post-3151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-portada-juarez","category-seguridad","category-seguridad-juarez","tag-destitucion-mandos-policiacos","tag-julio-cantu-gzz"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"predecessor-version":[{"id":64711,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/3151\/revisions\/64711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}