                       {"id":31665,"date":"2022-08-15T14:13:00","date_gmt":"2022-08-15T20:13:00","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=31665"},"modified":"2024-12-11T10:36:11","modified_gmt":"2024-12-11T16:36:11","slug":"incendio-en-una-iglesia-copta-en-egipto-deja-41-muertos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/incendio-en-una-iglesia-copta-en-egipto-deja-41-muertos\/","title":{"rendered":"Incendio en una iglesia Copta en Egipto deja 41 muertos"},"content":{"rendered":"<p>El Cairo.- Un incendio se origin\u00f3 ayer en una abarrotada iglesia ortodoxa copta durante los servicios matutinos en la capital de Egipto, la cual se llen\u00f3 r\u00e1pidamente de denso humo negro y deriv\u00f3 en la muerte de 41 feligreses, incluidos 15 ni\u00f1os.<\/p>\n<p>Varios miembros de la congregaci\u00f3n que quedaron atrapados saltaron desde los pisos superiores de la iglesia del M\u00e1rtir Abu Sefein para intentar escapar, dijeron testigos.<\/p>\n<p>En total, 16 personas resultaron heridas, entre ellos cuatro polic\u00edas involucrados en las labores de rescate. Se desconoce el origen del incendio en la iglesia ubicada en Imbaba, un vecindario de clase trabajadora, aunque de manera extraoficial se presume de un cortocircuito como origen del incendio.<\/p>\n<p>Las familias esperaban llorando afuera de la iglesia y de hospitales cercanos a recibir noticias sobre sus parientes que se encontraban en el templo.<\/p>\n<p>Im\u00e1genes de la escena que circularon por Internet mostraban muebles quemados, como mesas y sillas de madera. Se pudo ver a los bomberos apagando las llamas mientras otros llevaban a las v\u00edctimas hacia las ambulancias.<\/p>\n<p>Seg\u00fan testigos, varios menores se encontraban en el edificio de cuatro pisos, en el que hab\u00eda dos guarder\u00edas.<\/p>\n<p>Un total de 15 ni\u00f1os murieron, dijo Copts United, un sitio web que se enfoca en noticias cristianas.<\/p>\n<p>Seg\u00fan una lista de v\u00edctimas a la que Associated Press tuvo acceso, 20 fueron trasladadas al hospital p\u00fablico de Imbaba, entre ellas 10 ni\u00f1os.<\/p>\n<p>El obispo de la iglesia, Abdul Masih Bakhit, tambi\u00e9n se encontraba entre los muertos en la morgue del hospital. Otras 21 personas fueron llevadas a otros hospitales.<\/p>\n<p>Musa Ibrahim, portavoz de la iglesia ortodoxa copta, dijo a la Ap que entre los fallecidos hab\u00eda unos trillizos de 5 a\u00f1os, su madre, su abuela y una t\u00eda.<\/p>\n<p>El ministro de Salud, Jaled Abdel Ghafar, atribuy\u00f3 el n\u00famero de fallecimientos al humo y a una estampida desencadenada por personas que intentaban salir del lugar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cairo.- Un incendio se origin\u00f3 ayer en una abarrotada iglesia ortodoxa copta durante los servicios matutinos en la capital de Egipto, la cual se llen\u00f3 r\u00e1pidamente de denso humo negro y deriv\u00f3 en la muerte de 41 feligreses, incluidos 15 ni\u00f1os. Varios miembros de la congregaci\u00f3n que quedaron atrapados saltaron desde los pisos superiores [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":31666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[3896],"class_list":["post-31665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-fuente-la-jornada"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/31665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=31665"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/31665\/revisions"}],"predecessor-version":[{"id":77917,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/31665\/revisions\/77917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/31666"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=31665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=31665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=31665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}