                       {"id":33294,"date":"2022-10-07T15:39:27","date_gmt":"2022-10-07T21:39:27","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=33294"},"modified":"2024-12-11T10:40:10","modified_gmt":"2024-12-11T16:40:10","slug":"implementa-cadereyta-programa-va-por-ti","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/implementa-cadereyta-programa-va-por-ti\/","title":{"rendered":"Implementa Cadereyta programa &#8220;Va por ti&#8221;"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\">Cadereyta Jimenez, N.L.- Como parte de los trabajos de proximidad que realiza la Secretar\u00eda de Seguridad P\u00fablica de Cadereyta implement\u00f3 el programa \u201c\u00a1Va por ti!\u201d y este viernes arranc\u00f3 en la preparatoria CECyTE.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>El objetivo es realizar platicas preventivas, talleres y conferencias en los planteles educativos del municipio, es generar una cercan\u00eda con la comunidad, en la que se espera concientizar a los j\u00f3venes sobre temas de relaciones toxicas, prevenci\u00f3n de adicciones, prevenci\u00f3n al suicidio y violencia de g\u00e9nero.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cNuestro alcalde Cosme Leal est\u00e1 preocupado porque la Secretar\u00eda de Seguridad P\u00fablica tenga una proximidad con ustedes, si no la tenemos no podremos saber lo que est\u00e1 sucediendo en los planteles, en los hogares y en la comunidad, estamos para poder escuchar lo que les acontece, pero sobre todo poderlos orientar, guiar y acompa\u00f1ar\u201d, expres\u00f3 Carmen Garc\u00eda encargada de Proximidad Social de Cadereyta.<\/p>\n<p>&nbsp;<\/p>\n<p>La preocupaci\u00f3n del Gobierno es tener un acercamiento para brindarles la atenci\u00f3n adecuada, por ello se trabaja para prevenir alguna situaci\u00f3n de riesgo en todos los sectores de la sociedad y tener un Cadereyta libre de violencia.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u00edneas de auxilio: 911 y 070<\/p>\n<p>Secretar\u00eda de Seguridad P\u00fablica: 8282842111 \/8282691900<\/p>\n<p>Protecci\u00f3n Civil: 828284 25 25<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jimenez, N.L.- Como parte de los trabajos de proximidad que realiza la Secretar\u00eda de Seguridad P\u00fablica de Cadereyta implement\u00f3 el programa \u201c\u00a1Va por ti!\u201d y este viernes arranc\u00f3 en la preparatoria CECyTE. &nbsp; El objetivo es realizar platicas preventivas, talleres y conferencias en los planteles educativos del municipio, es generar una cercan\u00eda con la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":33295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[3840,4694],"class_list":["post-33294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-cadereyta-jimenez-nl","tag-va-por-ti"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/33294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=33294"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/33294\/revisions"}],"predecessor-version":[{"id":78722,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/33294\/revisions\/78722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/33295"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=33294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=33294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=33294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}