                       {"id":33964,"date":"2022-10-27T11:46:34","date_gmt":"2022-10-27T17:46:34","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=33964"},"modified":"2024-12-11T10:40:13","modified_gmt":"2024-12-11T16:40:13","slug":"lleva-paco-trevino-servicios-publicos-a-paseo-santa-fe","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/lleva-paco-trevino-servicios-publicos-a-paseo-santa-fe\/","title":{"rendered":"Lleva Paco Trevi\u00f1o servicios p\u00fablicos a Paseo Santa Fe"},"content":{"rendered":"<p><span style=\"font-size: 1rem;\">Ju\u00e1rez, N.L.- Esta ma\u00f1ana el alcalde de Ju\u00e1rez, Francisco Trevi\u00f1o Cant\u00fa estuvo recorriendo la colonia Paseo Santa Fe hasta donde llev\u00f3 todos los servicios p\u00fablicos para mejoramiento de las condiciones de dicha colonia.<\/span><\/p>\n<p>Se estuvieron haciendo labores de bacheo, deshierbe, limpieza en la plaza de la colonia y se atendi\u00f3 el alumbrado p\u00fablico; mientras por su parte, el alcalde juarense recorri\u00f3 algunas de las calles atendiendo quejas y solicitudes de los vecinos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Esta ma\u00f1ana el alcalde de Ju\u00e1rez, Francisco Trevi\u00f1o Cant\u00fa estuvo recorriendo la colonia Paseo Santa Fe hasta donde llev\u00f3 todos los servicios p\u00fablicos para mejoramiento de las condiciones de dicha colonia. Se estuvieron haciendo labores de bacheo, deshierbe, limpieza en la plaza de la colonia y se atendi\u00f3 el alumbrado p\u00fablico; mientras por [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":33965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3590,1684,3871],"class_list":["post-33964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-juarez-nl","tag-paco-trevino","tag-servicios-publicos"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/33964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=33964"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/33964\/revisions"}],"predecessor-version":[{"id":79029,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/33964\/revisions\/79029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/33965"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=33964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=33964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=33964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}